{"id":5600,"date":"2021-03-07T20:56:15","date_gmt":"2021-03-07T20:56:15","guid":{"rendered":"https:\/\/fishingadventure.nl\/?page_id=5600"},"modified":"2026-04-23T23:41:57","modified_gmt":"2026-04-23T22:41:57","slug":"home","status":"publish","type":"page","link":"https:\/\/www.fishingadventure.nl\/de\/","title":{"rendered":"Startseite"},"content":{"rendered":"<section class=\"section\" id=\"section_248342110\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse align-middle align-center\"  id=\"row-1191712121\">\n\n\n\t<div id=\"col-1888328692\" class=\"col medium-4 small-4 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<a href=\"https:\/\/bookings.fishingadventure.nl\/\" class=\"button primary is-xxsmall expand\" >\n\t\t<span>Stek B\u00fccher (NL)<\/span>\n\t<\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1888328692 > .col-inner {\n  padding: 0px 0px 0px 0px;\n  margin: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-2093920499\" class=\"col medium-4 small-4 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<a href=\"https:\/\/fishingadventure.recranet.com\/de\" class=\"button primary is-xxsmall expand\" target=\"_blank\" rel=\"noopener\">\n\t\t<span>angelplatz buchen (DE)<\/span>\n\t<\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2093920499 > .col-inner {\n  padding: 0px 0px 0px 0px;\n  margin: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1030639772\" class=\"col medium-4 small-4 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<a href=\"https:\/\/fishingadventure.recranet.com\/en\/\" class=\"button primary is-xxsmall expand\" target=\"_blank\" rel=\"noopener\">\n\t\t<span>Buchen Sie Ihr Schwimmen (EN)<\/span>\n\t<\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1030639772 > .col-inner {\n  padding: 0px 0px 0px 0px;\n  margin: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\n<style>\n#row-1191712121 > .col > .col-inner {\n  padding: 15px 3px 0px 3px;\n}\n<\/style>\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_248342110 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  background-color: rgb(220, 220, 220);\n}\n<\/style>\n\t<\/section>\n\t\n\n\n\t<section class=\"section\" id=\"section_152557000\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img decoding=\"async\" width=\"1920\" height=\"1035\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/Fishing-Adventure-Lake-Rutbekerveldweg-Enschede-het-grootste-betaalwater-van-Nederland-FABAITS.jpg?lossy=1&strip=1&webp=1\" class=\"bg attachment-original size-original lazyload\" alt=\"Fishing Adventure Lake het grootste betaalwater van Nederland\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/Fishing-Adventure-Lake-Rutbekerveldweg-Enschede-het-grootste-betaalwater-van-Nederland-FABAITS.jpg?lossy=1&amp;strip=1&amp;webp=1 1920w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/Fishing-Adventure-Lake-Rutbekerveldweg-Enschede-het-grootste-betaalwater-van-Nederland-FABAITS-510x275.jpg?lossy=1&amp;strip=1&amp;webp=1 510w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/Fishing-Adventure-Lake-Rutbekerveldweg-Enschede-het-grootste-betaalwater-van-Nederland-FABAITS-300x162.jpg?lossy=1&amp;strip=1&amp;webp=1 300w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/Fishing-Adventure-Lake-Rutbekerveldweg-Enschede-het-grootste-betaalwater-van-Nederland-FABAITS-1024x552.jpg?lossy=1&amp;strip=1&amp;webp=1 1024w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/Fishing-Adventure-Lake-Rutbekerveldweg-Enschede-het-grootste-betaalwater-van-Nederland-FABAITS-768x414.jpg?lossy=1&amp;strip=1&amp;webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/Fishing-Adventure-Lake-Rutbekerveldweg-Enschede-het-grootste-betaalwater-van-Nederland-FABAITS-1536x828.jpg?lossy=1&amp;strip=1&amp;webp=1 1536w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/Fishing-Adventure-Lake-Rutbekerveldweg-Enschede-het-grootste-betaalwater-van-Nederland-FABAITS-18x10.jpg?lossy=1&amp;strip=1&amp;webp=1 18w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/Fishing-Adventure-Lake-Rutbekerveldweg-Enschede-het-grootste-betaalwater-van-Nederland-FABAITS.jpg?size=204x110&amp;lossy=1&amp;strip=1&amp;webp=1 204w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/Fishing-Adventure-Lake-Rutbekerveldweg-Enschede-het-grootste-betaalwater-van-Nederland-FABAITS.jpg?size=408x220&amp;lossy=1&amp;strip=1&amp;webp=1 408w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/Fishing-Adventure-Lake-Rutbekerveldweg-Enschede-het-grootste-betaalwater-van-Nederland-FABAITS.jpg?size=612x330&amp;lossy=1&amp;strip=1&amp;webp=1 612w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1920px; --smush-placeholder-aspect-ratio: 1920\/1035;\" data-original-sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t<div class=\"section-bg-overlay absolute fill\"><\/div>\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse\"  id=\"row-1382614876\">\n\n\n\t<div id=\"col-1455331808\" class=\"col medium-11 small-12 large-7\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-148558001\" class=\"text\">\n\t\t\n\n<h2 class=\"uppercase\"><strong>SCH\u00d6NES UND GR\u00d6SSTES (44 Hektar)<br \/>PAYWATER DER NIEDERLANDE\u00a0<br \/><\/strong><\/h2>\n\t\t\n<style>\n#text-148558001 {\n  font-size: 1rem;\n  color: rgb(255, 255, 255);\n}\n#text-148558001 > * {\n  color: rgb(255, 255, 255);\n}\n@media (min-width:550px) {\n  #text-148558001 {\n    font-size: 1.35rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-348629640\" class=\"text\">\n\t\t\n\n<p><strong>\u00dcber 1.200 Karpfen bis zu 32,2 kg - St\u00f6re bis zu 2,56 m. <\/strong><strong>Gro\u00dfer Wels, Hecht, Zander, Barsch, Stripers und Blackbass.<\/strong><\/p>\n\t\t\n<style>\n#text-348629640 {\n  font-size: 1rem;\n  text-align: left;\n  color: rgb(255, 255, 255);\n}\n#text-348629640 > * {\n  color: rgb(255, 255, 255);\n}\n@media (min-width:550px) {\n  #text-348629640 {\n    font-size: 1rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"https:\/\/www.fishingadventure.nl\/de\/fishing-adventure-lake\/\" class=\"button primary hide-for-small\" style=\"padding:0px 10px 0px 10px;\">\n\t\t<span>Angeln Abenteuer See<\/span>\n\t<\/a>\n\n\n<a href=\"https:\/\/www.fishingadventure.nl\/de\/fishing-adventure-lagoon\/\" class=\"button primary hide-for-small\" style=\"padding:0px 10px 0px 10px;\">\n\t\t<span>Angeln Abenteuer Lagune<\/span>\n\t<\/a>\n\n\n\t<div id=\"gap-1799169248\" class=\"gap-element clearfix hide-for-small\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1799169248 {\n  padding-top: 50px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1455331808 > .col-inner {\n  padding: 0px 0px 0px 15px;\n  margin: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1455331808 > .col-inner {\n    padding: 0px 0px 0px 93px;\n  }\n}\n@media (min-width:850px) {\n  #col-1455331808 > .col-inner {\n    padding: 0px 0px 0px 10px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1107920343\" class=\"col medium-11 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<a href=\"https:\/\/www.bellyfiction.com\/\" target=\"_blank\" class=\"button primary is-small hide-for-small\" rel=\"noopener\" style=\"padding:0px 10px 0px 10px;\">\n\t\t<span>BellyFiction 2026<\/span>\n\t<\/a>\n\n\n<a href=\"https:\/\/www.fishingadventure.nl\/de\/karper-koppel-wedstrijd\/\" target=\"_blank\" class=\"button primary is-small hide-for-small\" rel=\"noopener\" style=\"padding:0px 18px 0px 10px;\">\n\t\t<span>Karpfenpaar-Rennen 2026<\/span>\n\t<\/a>\n\n\n<a href=\"https:\/\/www.fishingadventure.nl\/de\/big-fish-competitie\/\" class=\"button primary is-small hide-for-small\" style=\"padding:0px 10px 0px 10px;\">\n\t\t<span>Gro\u00dfe Fischspiele 2026<\/span>\n\t<\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1107920343 > .col-inner {\n  padding: 0px 0px 0px 15px;\n  margin: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1107920343 > .col-inner {\n    padding: 0px 0px 0px 93px;\n    margin: -50px 0px 0px 0px;\n  }\n}\n@media (min-width:850px) {\n  #col-1107920343 > .col-inner {\n    padding: 0px 0px 0px 10px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1286892250\" class=\"col show-for-small medium-7 small-12 large-7\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<a href=\"https:\/\/www.fishingadventure.nl\/de\/fishing-adventure-lake\/\" class=\"button primary is-smaller expand\">\n\t\t<span>Angeln Abenteuer See<\/span>\n\t<\/a>\n\n\n<a href=\"https:\/\/www.fishingadventure.nl\/de\/fishing-adventure-lagoon\/\" class=\"button primary is-smaller expand\">\n\t\t<span>Angeln Abenteuer Lagune<\/span>\n\t<\/a>\n\n\n<a href=\"https:\/\/www.bellyfiction.com\/\" class=\"button primary is-smaller expand\" target=\"_blank\" rel=\"noopener\">\n\t\t<span>BellyFiction 2025<\/span>\n\t<\/a>\n\n\n<a href=\"https:\/\/www.fishingadventure.nl\/de\/big-fish-competitie\/\" class=\"button primary is-smaller expand\">\n\t\t<span>Gro\u00dfe Fische Spiele 2025<\/span>\n\t<\/a>\n\n\n<a href=\"https:\/\/www.fishingadventure.nl\/de\/karper-koppel-wedstrijd\/\" class=\"button primary is-smaller expand\">\n\t\t<span>Karpfen-Paar Spiele 2025<\/span>\n\t<\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1286892250 > .col-inner {\n  padding: 0px 0px 0px 0px;\n  max-width: 90%;\n}\n@media (min-width:550px) {\n  #col-1286892250 > .col-inner {\n    padding: 0px 0px 60px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_152557000 {\n  padding-top: 62px;\n  padding-bottom: 62px;\n  min-height: 380px;\n}\n#section_152557000 .section-bg-overlay {\n  background-color: rgba(0, 0, 0, 0.285);\n}\n#section_152557000 .section-bg img {\n  object-position: 51% 22%;\n}\n@media (min-width:550px) {\n  #section_152557000 {\n    padding-top: 108px;\n    padding-bottom: 108px;\n  }\n  #section_152557000 .section-bg-overlay {\n    background-color: rgba(0, 0, 0, 0.442);\n  }\n}\n@media (min-width:850px) {\n  #section_152557000 {\n    padding-top: 141px;\n    padding-bottom: 141px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1660912574\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse\"  id=\"row-1625291026\">\n\n\n\t<div id=\"col-167905379\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner dark\" style=\"background-color:#127a3f;\" >\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-color:rgba(217, 217, 217, 0.547);border-width:0px 1px 0px 0px;\">\n\t<\/div>\n\t\t\t\n\n\t<div id=\"text-527994258\" class=\"text\">\n\t\t\n\n<h2>Angeln im See (das Rutbekerveld)<\/h2>\n<p>An diesem 44 Hektar gro\u00dfen Gew\u00e4sser k\u00f6nnen Sie 7 Tage die Woche, 24 Stunden am Tag von Ihrem eigenen Angelzelt oder einer der 2 komfortablen Angelh\u00fctten aus angeln. Der Rekordkarpfen ist 32,2 kg schwer und wurde am 31.12.2022 gefangen, der gr\u00f6\u00dfte St\u00f6r ist 2,56 m und der Rekordwels 2,36 m lang. Hinweis: Nur Fangen und Freilassen! Alle gefangenen Fische m\u00fcssen zur\u00fcckgegeben werden.<\/p>\n\t\t\n<style>\n#text-527994258 {\n  font-size: 1rem;\n  text-align: left;\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"https:\/\/www.fishingadventure.nl\/de\/fishing-adventure-lake\/\" class=\"button white\">\n\t\t<span>Weitere Informationen<\/span>\n\t<\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-167905379 > .col-inner {\n  margin: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-167905379 > .col-inner {\n    margin: 0px 0px 0px 0px;\n  }\n}\n@media (min-width:850px) {\n  #col-167905379 > .col-inner {\n    margin: -100px 0px 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-680834411\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:0px 0px 0px 0px;\">\n\t<\/div>\n\t\t\t\n\n\t<div id=\"text-1240671720\" class=\"text\">\n\t\t\n\n<h2>Angeln in der Lagune<\/h2>\n<p>Hier k\u00f6nnen Sie auf Karpfen, St\u00f6r, Wels, Streifen, Schwarzbarsch und vieles mehr angeln. Es ist auch m\u00f6glich, hier eine Firmenfeier, einen Familientag, einen Wettbewerb usw. in Kombination mit einem BBQ oder Buffet zu organisieren. Bitte beachten Sie: Catch and Release only, alle gefangenen Fische m\u00fcssen zur\u00fcckgesetzt werden!<\/p>\n\t\t\n<style>\n#text-1240671720 {\n  font-size: 1rem;\n  text-align: left;\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"https:\/\/www.fishingadventure.nl\/de\/fishing-adventure-lagoon\/\" class=\"button primary\">\n\t\t<span>Weitere Informationen<\/span>\n\t<\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-680834411 > .col-inner {\n  padding: 0px 0px 0px 0px;\n  margin: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-680834411 > .col-inner {\n    margin: 0px 0px 0px 0px;\n  }\n}\n@media (min-width:850px) {\n  #col-680834411 > .col-inner {\n    margin: -100px 0px 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\n<style>\n#row-1625291026 > .col > .col-inner {\n  padding: 25px 35px 25px 35px;\n  background-color: rgb(255,255,255);\n}\n<\/style>\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1660912574 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_471259657\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:0px 0px 0px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row align-middle\"  id=\"row-125725580\">\n\n\n\t<div id=\"col-863240834\" class=\"col hide-for-medium medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-3958806104\" class=\"text\">\n\t\t\n\n<h2>Erleben Sie<\/h2>\n<p>Fishing Adventure, das gr\u00f6\u00dfte Lohngew\u00e4sser der Niederlande, ist kein gew\u00f6hnlicher Angelplatz - es ist ein riesiges Abenteuer in einer atemberaubenden, waldreichen Umgebung, in der jeder Wurf zu einer Geschichte werden kann. Umgeben von hohen B\u00e4umen, Vogelgezwitscher und dem frischen Duft des Waldes w\u00e4hnt man sich in einer Oase der Ruhe und erlebt gleichzeitig das Spektakel des Angelns. Hier dreht sich alles um Spannung, Natur und das Unerwartete: Man wei\u00df nie, wann der Riesenkarpfen, der glitschige Aal oder der feurige Hecht pl\u00f6tzlich am Haken h\u00e4ngt.<\/p>\n<p>Hier f\u00fchlt sich jeder Fang gro\u00df an. Das Adrenalin schie\u00dft durch Ihren K\u00f6rper, w\u00e4hrend Sie die Leine straff halten und mit einem m\u00e4chtigen Exemplar k\u00e4mpfen, das nicht so leicht aufgibt. Und wenn Sie ihn dann am Ufer haben, wartet der stolze Moment, ihn zu bewundern, ein Foto zu machen und die Geschichte f\u00fcr immer festzuhalten. Ganz gleich, ob Sie sich f\u00fcr das Abenteuer am gro\u00dfen Angelsee oder f\u00fcr einen der intimeren Pl\u00e4tze tief im Gr\u00fcnen entscheiden, \u00fcberall sp\u00fcren Sie die Magie der Natur und den Nervenkitzel des Angelns.<\/p>\n\t\t\n<style>\n#text-3958806104 {\n  font-size: 1.05rem;\n  line-height: 1.75;\n  text-align: left;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1964084257\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-2545558262\" class=\"text show-for-small\">\n\t\t\n\n<h2>Gefangen bei Fishing Adventure<\/h2>\n\t\t\t<\/div>\n\t\n<div class=\"slider-wrapper relative\" id=\"slider-1417714235\" >\n    <div class=\"slider slider-nav-circle slider-nav-large slider-nav-light slider-style-normal\"\n        data-flickity-options='{            \"cellAlign\": \"center\",            \"imagesLoaded\": true,            \"lazyLoad\": 1,            \"freeScroll\": false,            \"wrapAround\": true,            \"autoPlay\": 6000,            \"pauseAutoPlayOnHover\" : true,            \"prevNextButtons\": true,            \"contain\" : true,            \"adaptiveHeight\" : true,            \"dragThreshold\" : 10,            \"percentPosition\": true,            \"pageDots\": true,            \"rightToLeft\": false,            \"draggable\": true,            \"selectedAttraction\": 0.1,            \"parallax\" : 0,            \"friction\": 0.6        }'\n        >\n        \n\n\n  <div class=\"banner has-hover\" id=\"banner-1700488197\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img decoding=\"async\" width=\"1020\" height=\"680\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/2019-227-1024x683.jpg?lossy=1&strip=1&webp=1\" class=\"bg attachment-large size-large lazyload\" alt=\"\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/2019-227-1024x683.jpg?lossy=1&amp;strip=1&amp;webp=1 1024w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/2019-227-scaled-510x340.jpg?lossy=1&amp;strip=1&amp;webp=1 510w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/2019-227-300x200.jpg?lossy=1&amp;strip=1&amp;webp=1 300w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/2019-227-768x513.jpg?lossy=1&amp;strip=1&amp;webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/2019-227-1536x1025.jpg?lossy=1&amp;strip=1&amp;webp=1 1536w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/2019-227-2048x1367.jpg?lossy=1&amp;strip=1&amp;webp=1 2048w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/2019-227-18x12.jpg?lossy=1&amp;strip=1&amp;webp=1 18w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/2019-227-scaled.jpg?size=204x136&amp;lossy=1&amp;strip=1&amp;webp=1 204w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/2019-227-scaled.jpg?size=408x272&amp;lossy=1&amp;strip=1&amp;webp=1 408w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/2019-227-scaled.jpg?size=612x408&amp;lossy=1&amp;strip=1&amp;webp=1 612w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1020px; --smush-placeholder-aspect-ratio: 1020\/680;\" data-original-sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>                                    \n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:5px 0px 0px 0px;\">\n\t<\/div>\n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1700488197 {\n  padding-top: 250px;\n  background-color: rgb(255, 255, 255);\n}\n#banner-1700488197 .banner-bg img {\n  object-position: 37% 55%;\n}\n@media (min-width:550px) {\n  #banner-1700488197 {\n    padding-top: 365px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover\" id=\"banner-1543916343\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img decoding=\"async\" width=\"1020\" height=\"574\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/06\/IMG-20210603-2.42-m-1024x576.jpg?lossy=1&strip=1&webp=1\" class=\"bg attachment-large size-large lazyload\" alt=\"Wederom nieuw meerrecord Beluga: 2.42 meter\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/06\/IMG-20210603-2.42-m-1024x576.jpg?lossy=1&amp;strip=1&amp;webp=1 1024w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/06\/IMG-20210603-2.42-m-300x169.jpg?lossy=1&amp;strip=1&amp;webp=1 300w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/06\/IMG-20210603-2.42-m-768x432.jpg?lossy=1&amp;strip=1&amp;webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/06\/IMG-20210603-2.42-m-1536x864.jpg?lossy=1&amp;strip=1&amp;webp=1 1536w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/06\/IMG-20210603-2.42-m-600x338.jpg?lossy=1&amp;strip=1&amp;webp=1 600w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/06\/IMG-20210603-2.42-m.jpg?lossy=1&amp;strip=1&amp;webp=1 1600w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/06\/IMG-20210603-2.42-m.jpg?size=204x115&amp;lossy=1&amp;strip=1&amp;webp=1 204w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/06\/IMG-20210603-2.42-m.jpg?size=408x230&amp;lossy=1&amp;strip=1&amp;webp=1 408w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1020px; --smush-placeholder-aspect-ratio: 1020\/574;\" data-original-sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>                                    \n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:5px 0px 0px 0px;\">\n\t<\/div>\n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1543916343 {\n  padding-top: 250px;\n  background-color: rgb(255, 255, 255);\n}\n#banner-1543916343 .banner-bg img {\n  object-position: 50% 41%;\n}\n@media (min-width:550px) {\n  #banner-1543916343 {\n    padding-top: 400px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover\" id=\"banner-719655982\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img decoding=\"async\" width=\"1020\" height=\"765\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/05\/2022-12-31-322-KG-5-1024x768.jpg?lossy=1&strip=1&webp=1\" class=\"bg attachment-large size-large lazyload\" alt=\"\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/05\/2022-12-31-322-KG-5-1024x768.jpg?lossy=1&amp;strip=1&amp;webp=1 1024w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/05\/2022-12-31-322-KG-5-300x225.jpg?lossy=1&amp;strip=1&amp;webp=1 300w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/05\/2022-12-31-322-KG-5-768x576.jpg?lossy=1&amp;strip=1&amp;webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/05\/2022-12-31-322-KG-5-1536x1152.jpg?lossy=1&amp;strip=1&amp;webp=1 1536w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/05\/2022-12-31-322-KG-5-16x12.jpg?lossy=1&amp;strip=1&amp;webp=1 16w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/05\/2022-12-31-322-KG-5-510x383.jpg?lossy=1&amp;strip=1&amp;webp=1 510w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/05\/2022-12-31-322-KG-5.jpg?lossy=1&amp;strip=1&amp;webp=1 1600w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/05\/2022-12-31-322-KG-5.jpg?size=204x153&amp;lossy=1&amp;strip=1&amp;webp=1 204w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/05\/2022-12-31-322-KG-5.jpg?size=408x306&amp;lossy=1&amp;strip=1&amp;webp=1 408w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/05\/2022-12-31-322-KG-5.jpg?size=612x459&amp;lossy=1&amp;strip=1&amp;webp=1 612w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1020px; --smush-placeholder-aspect-ratio: 1020\/765;\" data-original-sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>                                    \n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:5px 0px 0px 0px;\">\n\t<\/div>\n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-719655982 {\n  padding-top: 250px;\n  background-color: rgb(255, 255, 255);\n}\n#banner-719655982 .banner-bg img {\n  object-position: 49% 99%;\n}\n@media (min-width:550px) {\n  #banner-719655982 {\n    padding-top: 400px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover\" id=\"banner-985500151\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img decoding=\"async\" width=\"1020\" height=\"765\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/IMG-20220916-WA0057-kopie-1024x768.jpg?lossy=1&strip=1&webp=1\" class=\"bg attachment-large size-large lazyload\" alt=\"\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/IMG-20220916-WA0057-kopie-1024x768.jpg?lossy=1&amp;strip=1&amp;webp=1 1024w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/IMG-20220916-WA0057-kopie-510x383.jpg?lossy=1&amp;strip=1&amp;webp=1 510w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/IMG-20220916-WA0057-kopie-300x225.jpg?lossy=1&amp;strip=1&amp;webp=1 300w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/IMG-20220916-WA0057-kopie-768x576.jpg?lossy=1&amp;strip=1&amp;webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/IMG-20220916-WA0057-kopie-1536x1152.jpg?lossy=1&amp;strip=1&amp;webp=1 1536w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/IMG-20220916-WA0057-kopie-16x12.jpg?lossy=1&amp;strip=1&amp;webp=1 16w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/IMG-20220916-WA0057-kopie.jpg?lossy=1&amp;strip=1&amp;webp=1 2048w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/IMG-20220916-WA0057-kopie.jpg?size=204x153&amp;lossy=1&amp;strip=1&amp;webp=1 204w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/IMG-20220916-WA0057-kopie.jpg?size=408x306&amp;lossy=1&amp;strip=1&amp;webp=1 408w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/IMG-20220916-WA0057-kopie.jpg?size=612x459&amp;lossy=1&amp;strip=1&amp;webp=1 612w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1020px; --smush-placeholder-aspect-ratio: 1020\/765;\" data-original-sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>                                    \n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:5px 0px 0px 0px;\">\n\t<\/div>\n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-985500151 {\n  padding-top: 250px;\n  background-color: rgb(255, 255, 255);\n}\n#banner-985500151 .banner-bg img {\n  object-position: 38% 76%;\n}\n@media (min-width:550px) {\n  #banner-985500151 {\n    padding-top: 400px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover\" id=\"banner-1619302691\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img decoding=\"async\" width=\"1020\" height=\"765\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/IMG-20220513-2.00-meter-kopie-1024x768.jpg?lossy=1&strip=1&webp=1\" class=\"bg attachment-large size-large lazyload\" alt=\"\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/IMG-20220513-2.00-meter-kopie-1024x768.jpg?lossy=1&amp;strip=1&amp;webp=1 1024w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/IMG-20220513-2.00-meter-kopie-510x383.jpg?lossy=1&amp;strip=1&amp;webp=1 510w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/IMG-20220513-2.00-meter-kopie-300x225.jpg?lossy=1&amp;strip=1&amp;webp=1 300w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/IMG-20220513-2.00-meter-kopie-768x576.jpg?lossy=1&amp;strip=1&amp;webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/IMG-20220513-2.00-meter-kopie-1536x1152.jpg?lossy=1&amp;strip=1&amp;webp=1 1536w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/IMG-20220513-2.00-meter-kopie-16x12.jpg?lossy=1&amp;strip=1&amp;webp=1 16w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/IMG-20220513-2.00-meter-kopie.jpg?lossy=1&amp;strip=1&amp;webp=1 2048w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/IMG-20220513-2.00-meter-kopie.jpg?size=204x153&amp;lossy=1&amp;strip=1&amp;webp=1 204w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/IMG-20220513-2.00-meter-kopie.jpg?size=408x306&amp;lossy=1&amp;strip=1&amp;webp=1 408w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/IMG-20220513-2.00-meter-kopie.jpg?size=612x459&amp;lossy=1&amp;strip=1&amp;webp=1 612w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1020px; --smush-placeholder-aspect-ratio: 1020\/765;\" data-original-sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>                                    \n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:5px 0px 0px 0px;\">\n\t<\/div>\n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1619302691 {\n  padding-top: 250px;\n  background-color: rgb(255, 255, 255);\n}\n#banner-1619302691 .banner-bg img {\n  object-position: 37% 86%;\n}\n@media (min-width:550px) {\n  #banner-1619302691 {\n    padding-top: 400px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover\" id=\"banner-2013364968\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img decoding=\"async\" width=\"1020\" height=\"771\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/IMG-20220731-46-pond-r-1024x774.jpg?lossy=1&strip=1&webp=1\" class=\"bg attachment-large size-large lazyload\" alt=\"\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/IMG-20220731-46-pond-r-1024x774.jpg?lossy=1&amp;strip=1&amp;webp=1 1024w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/IMG-20220731-46-pond-r-510x386.jpg?lossy=1&amp;strip=1&amp;webp=1 510w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/IMG-20220731-46-pond-r-300x227.jpg?lossy=1&amp;strip=1&amp;webp=1 300w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/IMG-20220731-46-pond-r-768x581.jpg?lossy=1&amp;strip=1&amp;webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/IMG-20220731-46-pond-r-16x12.jpg?lossy=1&amp;strip=1&amp;webp=1 16w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/IMG-20220731-46-pond-r.jpg?lossy=1&amp;strip=1&amp;webp=1 1074w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/IMG-20220731-46-pond-r.jpg?size=204x154&amp;lossy=1&amp;strip=1&amp;webp=1 204w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/IMG-20220731-46-pond-r.jpg?size=408x308&amp;lossy=1&amp;strip=1&amp;webp=1 408w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/IMG-20220731-46-pond-r.jpg?size=612x463&amp;lossy=1&amp;strip=1&amp;webp=1 612w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1020px; --smush-placeholder-aspect-ratio: 1020\/771;\" data-original-sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>                                    \n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:5px 0px 0px 0px;\">\n\t<\/div>\n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-2013364968 {\n  padding-top: 250px;\n  background-color: rgb(255, 255, 255);\n}\n#banner-2013364968 .banner-bg img {\n  object-position: 41% 33%;\n}\n@media (min-width:550px) {\n  #banner-2013364968 {\n    padding-top: 400px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_471259657 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n@media (min-width:550px) {\n  #section_471259657 {\n    padding-top: 45px;\n    padding-bottom: 45px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section has-parallax\" id=\"section_1471786367\">\n\t\t<div class=\"section-bg fill\" data-parallax-container=\".section\" data-parallax-background data-parallax=\"-5\">\n\t\t\t<img decoding=\"async\" width=\"1600\" height=\"1200\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/05\/Vissershut-in-het-donker-met-verlichting-1.jpg?lossy=1&strip=1&webp=1\" class=\"bg attachment-original size-original lazyload\" alt=\"\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/05\/Vissershut-in-het-donker-met-verlichting-1.jpg?lossy=1&amp;strip=1&amp;webp=1 1600w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/05\/Vissershut-in-het-donker-met-verlichting-1-300x225.jpg?lossy=1&amp;strip=1&amp;webp=1 300w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/05\/Vissershut-in-het-donker-met-verlichting-1-1024x768.jpg?lossy=1&amp;strip=1&amp;webp=1 1024w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/05\/Vissershut-in-het-donker-met-verlichting-1-768x576.jpg?lossy=1&amp;strip=1&amp;webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/05\/Vissershut-in-het-donker-met-verlichting-1-1536x1152.jpg?lossy=1&amp;strip=1&amp;webp=1 1536w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/05\/Vissershut-in-het-donker-met-verlichting-1-600x450.jpg?lossy=1&amp;strip=1&amp;webp=1 600w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/05\/Vissershut-in-het-donker-met-verlichting-1.jpg?size=204x153&amp;lossy=1&amp;strip=1&amp;webp=1 204w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/05\/Vissershut-in-het-donker-met-verlichting-1.jpg?size=408x306&amp;lossy=1&amp;strip=1&amp;webp=1 408w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1600px; --smush-placeholder-aspect-ratio: 1600\/1200;\" data-original-sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t\t\t\t\t\t<div class=\"section-bg-overlay absolute fill\"><\/div>\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:0px 0px 0px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse row-full-width align-equal\"  id=\"row-1661683869\">\n\n\n\t<div id=\"col-54706640\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-1426008484\" class=\"text\">\n\t\t\n\n<h2>Buchen Sie eine unserer Fischerh\u00fctten<\/h2>\n\t\t\n<style>\n#text-1426008484 {\n  font-size: 1.6rem;\n  text-align: center;\n  color: rgb(255, 255, 255);\n}\n#text-1426008484 > * {\n  color: rgb(255, 255, 255);\n}\n@media (min-width:550px) {\n  #text-1426008484 {\n    font-size: 1.3rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-3444197398\" class=\"text\">\n\t\t\n\n<p>M\u00f6chten Sie Ihren Angeltag abrunden und das Abenteuer mit einer \u00dcbernachtung inmitten der Natur verl\u00e4ngern? Dann buchen Sie eine unserer gem\u00fctlichen Fischerh\u00fctten! Diese gem\u00fctlichen, komplett ausgestatteten H\u00fctten liegen direkt am Wasser und bieten Ihnen den perfekten Ausgangspunkt f\u00fcr das Angeln am fr\u00fchen Morgen und am sp\u00e4ten Abend.\u00a0<\/p>\n\t\t\n<style>\n#text-3444197398 {\n  font-size: 1rem;\n  text-align: center;\n  color: rgb(255, 255, 255);\n}\n#text-3444197398 > * {\n  color: rgb(255, 255, 255);\n}\n@media (min-width:550px) {\n  #text-3444197398 {\n    font-size: 1.2rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"https:\/\/www.fishingadventure.nl\/de\/faciliteiten\/vissershut\/\" class=\"button white\">\n\t\t<span>Unsere Fischerh\u00fctten<\/span>\n\t<\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-54706640 > .col-inner {\n  padding: 62px 15px 49px 15px;\n}\n@media (min-width:550px) {\n  #col-54706640 > .col-inner {\n    padding: 125px 65px 125px 65px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1471786367 {\n  padding-top: 75px;\n  padding-bottom: 75px;\n}\n#section_1471786367 .section-bg-overlay {\n  background-color: rgba(0, 0, 0, 0.645);\n}\n#section_1471786367 .section-bg img {\n  object-position: 55% 39%;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_104511355\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:0px 0px 0px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row align-middle\"  id=\"row-632026417\">\n\n\n\t<div id=\"col-1026212491\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"slider-wrapper relative\" id=\"slider-1707407201\" >\n    <div class=\"slider slider-nav-circle slider-nav-large slider-nav-light slider-style-normal\"\n        data-flickity-options='{            \"cellAlign\": \"center\",            \"imagesLoaded\": true,            \"lazyLoad\": 1,            \"freeScroll\": false,            \"wrapAround\": true,            \"autoPlay\": 6000,            \"pauseAutoPlayOnHover\" : true,            \"prevNextButtons\": true,            \"contain\" : true,            \"adaptiveHeight\" : true,            \"dragThreshold\" : 10,            \"percentPosition\": true,            \"pageDots\": true,            \"rightToLeft\": false,            \"draggable\": true,            \"selectedAttraction\": 0.1,            \"parallax\" : 0,            \"friction\": 0.6        }'\n        >\n        \n\n\n  <div class=\"banner has-hover\" id=\"banner-2050765881\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img decoding=\"async\" width=\"1020\" height=\"765\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/02\/barbecue-fishing-adventure-1024x768.jpg?lossy=1&strip=1&webp=1\" class=\"bg attachment-large size-large lazyload\" alt=\"\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/02\/barbecue-fishing-adventure-1024x768.jpg?lossy=1&amp;strip=1&amp;webp=1 1024w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/02\/barbecue-fishing-adventure-300x225.jpg?lossy=1&amp;strip=1&amp;webp=1 300w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/02\/barbecue-fishing-adventure-768x576.jpg?lossy=1&amp;strip=1&amp;webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/02\/barbecue-fishing-adventure-16x12.jpg?lossy=1&amp;strip=1&amp;webp=1 16w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/02\/barbecue-fishing-adventure-510x383.jpg?lossy=1&amp;strip=1&amp;webp=1 510w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/02\/barbecue-fishing-adventure.jpg?lossy=1&amp;strip=1&amp;webp=1 1280w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/02\/barbecue-fishing-adventure.jpg?size=204x153&amp;lossy=1&amp;strip=1&amp;webp=1 204w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/02\/barbecue-fishing-adventure.jpg?size=408x306&amp;lossy=1&amp;strip=1&amp;webp=1 408w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/02\/barbecue-fishing-adventure.jpg?size=612x459&amp;lossy=1&amp;strip=1&amp;webp=1 612w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1020px; --smush-placeholder-aspect-ratio: 1020\/765;\" data-original-sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>                                    \n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:5px 0px 0px 0px;\">\n\t<\/div>\n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-2050765881 {\n  padding-top: 250px;\n  background-color: rgb(255, 255, 255);\n}\n#banner-2050765881 .banner-bg img {\n  object-position: 56% 73%;\n}\n@media (min-width:550px) {\n  #banner-2050765881 {\n    padding-top: 400px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover\" id=\"banner-674143566\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img decoding=\"async\" width=\"1020\" height=\"765\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/02\/FA-Keuken-bellyfiction-interacctieve-map-1024x768.jpg?lossy=1&strip=1&webp=1\" class=\"bg attachment-large size-large lazyload\" alt=\"\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/02\/FA-Keuken-bellyfiction-interacctieve-map-1024x768.jpg?lossy=1&amp;strip=1&amp;webp=1 1024w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/02\/FA-Keuken-bellyfiction-interacctieve-map-300x225.jpg?lossy=1&amp;strip=1&amp;webp=1 300w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/02\/FA-Keuken-bellyfiction-interacctieve-map-768x576.jpg?lossy=1&amp;strip=1&amp;webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/02\/FA-Keuken-bellyfiction-interacctieve-map-1536x1152.jpg?lossy=1&amp;strip=1&amp;webp=1 1536w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/02\/FA-Keuken-bellyfiction-interacctieve-map-16x12.jpg?lossy=1&amp;strip=1&amp;webp=1 16w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/02\/FA-Keuken-bellyfiction-interacctieve-map-510x383.jpg?lossy=1&amp;strip=1&amp;webp=1 510w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/02\/FA-Keuken-bellyfiction-interacctieve-map.jpg?lossy=1&amp;strip=1&amp;webp=1 2000w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/02\/FA-Keuken-bellyfiction-interacctieve-map.jpg?size=204x153&amp;lossy=1&amp;strip=1&amp;webp=1 204w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/02\/FA-Keuken-bellyfiction-interacctieve-map.jpg?size=408x306&amp;lossy=1&amp;strip=1&amp;webp=1 408w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/02\/FA-Keuken-bellyfiction-interacctieve-map.jpg?size=612x459&amp;lossy=1&amp;strip=1&amp;webp=1 612w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1020px; --smush-placeholder-aspect-ratio: 1020\/765;\" data-original-sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>                                    \n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:5px 0px 0px 0px;\">\n\t<\/div>\n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-674143566 {\n  padding-top: 250px;\n  background-color: rgb(255,255,255);\n}\n@media (min-width:550px) {\n  #banner-674143566 {\n    padding-top: 400px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover\" id=\"banner-1070007721\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img decoding=\"async\" width=\"1020\" height=\"765\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/02\/20230423-BBQ-Mel-1024x768.jpg?lossy=1&strip=1&webp=1\" class=\"bg attachment-large size-large lazyload\" alt=\"\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/02\/20230423-BBQ-Mel-1024x768.jpg?lossy=1&amp;strip=1&amp;webp=1 1024w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/02\/20230423-BBQ-Mel-300x225.jpg?lossy=1&amp;strip=1&amp;webp=1 300w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/02\/20230423-BBQ-Mel-768x576.jpg?lossy=1&amp;strip=1&amp;webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/02\/20230423-BBQ-Mel-16x12.jpg?lossy=1&amp;strip=1&amp;webp=1 16w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/02\/20230423-BBQ-Mel-510x383.jpg?lossy=1&amp;strip=1&amp;webp=1 510w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/02\/20230423-BBQ-Mel.jpg?lossy=1&amp;strip=1&amp;webp=1 1280w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/02\/20230423-BBQ-Mel.jpg?size=204x153&amp;lossy=1&amp;strip=1&amp;webp=1 204w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/02\/20230423-BBQ-Mel.jpg?size=408x306&amp;lossy=1&amp;strip=1&amp;webp=1 408w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/02\/20230423-BBQ-Mel.jpg?size=612x459&amp;lossy=1&amp;strip=1&amp;webp=1 612w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1020px; --smush-placeholder-aspect-ratio: 1020\/765;\" data-original-sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>                                    \n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:5px 0px 0px 0px;\">\n\t<\/div>\n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1070007721 {\n  padding-top: 250px;\n  background-color: rgb(255, 255, 255);\n}\n#banner-1070007721 .banner-bg img {\n  object-position: 10% 39%;\n}\n@media (min-width:550px) {\n  #banner-1070007721 {\n    padding-top: 400px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover\" id=\"banner-1755228310\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img decoding=\"async\" width=\"1020\" height=\"765\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/03\/Salade-bbq-fishing-adventure-enschede-1024x768.png?lossy=1&strip=1&webp=1\" class=\"bg attachment-large size-large lazyload\" alt=\"Salade bbq - fishing adventure enschede\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/03\/Salade-bbq-fishing-adventure-enschede-1024x768.png?lossy=1&amp;strip=1&amp;webp=1 1024w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/03\/Salade-bbq-fishing-adventure-enschede-300x225.png?lossy=1&amp;strip=1&amp;webp=1 300w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/03\/Salade-bbq-fishing-adventure-enschede-768x576.png?lossy=1&amp;strip=1&amp;webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/03\/Salade-bbq-fishing-adventure-enschede-1536x1152.png?lossy=1&amp;strip=1&amp;webp=1 1536w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/03\/Salade-bbq-fishing-adventure-enschede-16x12.png?lossy=1&amp;strip=1&amp;webp=1 16w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/03\/Salade-bbq-fishing-adventure-enschede-510x383.png?lossy=1&amp;strip=1&amp;webp=1 510w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/03\/Salade-bbq-fishing-adventure-enschede.png?lossy=1&amp;strip=1&amp;webp=1 2000w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/03\/Salade-bbq-fishing-adventure-enschede.png?size=204x153&amp;lossy=1&amp;strip=1&amp;webp=1 204w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/03\/Salade-bbq-fishing-adventure-enschede.png?size=408x306&amp;lossy=1&amp;strip=1&amp;webp=1 408w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/03\/Salade-bbq-fishing-adventure-enschede.png?size=612x459&amp;lossy=1&amp;strip=1&amp;webp=1 612w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1020px; --smush-placeholder-aspect-ratio: 1020\/765;\" data-original-sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>                                    \n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:5px 0px 0px 0px;\">\n\t<\/div>\n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1755228310 {\n  padding-top: 250px;\n  background-color: rgb(255, 255, 255);\n}\n#banner-1755228310 .banner-bg img {\n  object-position: 56% 73%;\n}\n@media (min-width:550px) {\n  #banner-1755228310 {\n    padding-top: 400px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover\" id=\"banner-1158687185\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img decoding=\"async\" width=\"768\" height=\"1024\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/03\/Foto-bbq-fa-salade-768x1024.png?lossy=1&strip=1&webp=1\" class=\"bg attachment-large size-large lazyload\" alt=\"Salade bbq fishing adventure verjaardagsfeest\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/03\/Foto-bbq-fa-salade-768x1024.png?lossy=1&amp;strip=1&amp;webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/03\/Foto-bbq-fa-salade-225x300.png?lossy=1&amp;strip=1&amp;webp=1 225w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/03\/Foto-bbq-fa-salade-1152x1536.png?lossy=1&amp;strip=1&amp;webp=1 1152w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/03\/Foto-bbq-fa-salade-9x12.png?lossy=1&amp;strip=1&amp;webp=1 9w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/03\/Foto-bbq-fa-salade-510x680.png?lossy=1&amp;strip=1&amp;webp=1 510w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/03\/Foto-bbq-fa-salade.png?lossy=1&amp;strip=1&amp;webp=1 1200w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/03\/Foto-bbq-fa-salade.png?size=408x544&amp;lossy=1&amp;strip=1&amp;webp=1 408w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/03\/Foto-bbq-fa-salade.png?size=612x816&amp;lossy=1&amp;strip=1&amp;webp=1 612w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 768px; --smush-placeholder-aspect-ratio: 768\/1024;\" data-original-sizes=\"(max-width: 768px) 100vw, 768px\" \/>                                    \n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:5px 0px 0px 0px;\">\n\t<\/div>\n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1158687185 {\n  padding-top: 250px;\n  background-color: rgb(255, 255, 255);\n}\n#banner-1158687185 .banner-bg img {\n  object-position: 56% 73%;\n}\n@media (min-width:550px) {\n  #banner-1158687185 {\n    padding-top: 400px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover\" id=\"banner-468136890\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img decoding=\"async\" width=\"768\" height=\"1024\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/03\/Fishing-Adventure-bbq-assortiment-enschede-768x1024.png?lossy=1&strip=1&webp=1\" class=\"bg attachment-large size-large lazyload\" alt=\"Fishing Adventure - bbq assortiment - enschede\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/03\/Fishing-Adventure-bbq-assortiment-enschede-768x1024.png?lossy=1&amp;strip=1&amp;webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/03\/Fishing-Adventure-bbq-assortiment-enschede-225x300.png?lossy=1&amp;strip=1&amp;webp=1 225w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/03\/Fishing-Adventure-bbq-assortiment-enschede-1152x1536.png?lossy=1&amp;strip=1&amp;webp=1 1152w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/03\/Fishing-Adventure-bbq-assortiment-enschede-9x12.png?lossy=1&amp;strip=1&amp;webp=1 9w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/03\/Fishing-Adventure-bbq-assortiment-enschede-510x680.png?lossy=1&amp;strip=1&amp;webp=1 510w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/03\/Fishing-Adventure-bbq-assortiment-enschede.png?lossy=1&amp;strip=1&amp;webp=1 1500w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/03\/Fishing-Adventure-bbq-assortiment-enschede.png?size=408x544&amp;lossy=1&amp;strip=1&amp;webp=1 408w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/03\/Fishing-Adventure-bbq-assortiment-enschede.png?size=612x816&amp;lossy=1&amp;strip=1&amp;webp=1 612w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 768px; --smush-placeholder-aspect-ratio: 768\/1024;\" data-original-sizes=\"(max-width: 768px) 100vw, 768px\" \/>                                    \n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:5px 0px 0px 0px;\">\n\t<\/div>\n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-468136890 {\n  padding-top: 250px;\n  background-color: rgb(255, 255, 255);\n}\n#banner-468136890 .banner-bg img {\n  object-position: 56% 73%;\n}\n@media (min-width:550px) {\n  #banner-468136890 {\n    padding-top: 400px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1079185211\" class=\"col medium-6 small-12 large-6 small-col-first\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-1561345181\" class=\"text hide-for-medium\">\n\t\t\n\n<h2>Paket<\/h2>\n<p>Im Fishing Adventure, dem gr\u00f6\u00dften Lohngew\u00e4sser der Niederlande, ist der BBQ Lake die ultimative Endstation f\u00fcr ein unvergessliches Grillerlebnis! Unser Barbecue-Men\u00fc, zusammengestellt mit dem besten Grillfleisch vom \u00f6rtlichen Metzger aus der Region Twente, garantiert ein schmackhaftes Erlebnis. Lassen Sie sich \u00fcberraschen von k\u00f6stlichen Specksteaks, zarten Steaks, perfekten Burgern und gut gew\u00fcrzten Schweinefilet- und Bavettenspie\u00dfen - alles meisterhaft auf dem Grill zubereitet.<\/p>\n<p>Und vergessen Sie nicht die Beilagen! Genie\u00dfen Sie knuspriges Baguette und cremigen Kartoffel- und Rindfleischsalat mit einer Auswahl an k\u00f6stlichen kalten und warmen Saucen.<\/p>\n<p>Ob Sie die entspannte Atmosph\u00e4re unter unserem Adventure Stretch-Zelt mit eigener Bar oder die Gem\u00fctlichkeit der Lake Bar bevorzugen, beide Orte bieten den perfekten Rahmen f\u00fcr Ihr BBQ-Abenteuer.<\/p>\n\t\t\n<style>\n#text-1561345181 {\n  font-size: 1.05rem;\n  line-height: 1.75;\n  text-align: left;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-3568998654\" class=\"text show-for-medium\">\n\t\t\n\n<h2>Paket<\/h2>\n<p>Bei Fishing Adventure ist der BBQ Lake die ultimative Endstation f\u00fcr ein unvergessliches Grillerlebnis! Unser Grillmen\u00fc, zusammengestellt mit dem besten Grillfleisch vom \u00f6rtlichen Metzger aus der Region Twente, garantiert ein schmackhaftes Erlebnis.<\/p>\n\t\t\n<style>\n#text-3568998654 {\n  font-size: 1.05rem;\n  line-height: 1.75;\n  text-align: left;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1079185211 > .col-inner {\n  padding: 19px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_104511355 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  background-color: rgb(250, 250, 250);\n}\n@media (min-width:550px) {\n  #section_104511355 {\n    padding-top: 60px;\n    padding-bottom: 60px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1256789935\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-small\"  id=\"row-189033014\">\n\n\n\t<div id=\"col-764700030\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h2>Videos von Fishing Adventure<\/h2>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-764700030 > .col-inner {\n  margin: 10px 0px -10px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-675534407\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"video video-fit mb\" style=\"padding-top:56.25%;\"><iframe title=\"DIKKE KARPERS VANGEN IN NEDERLAND | MINI DOCUMENTARY | PB PRODUCTS (mit englischen Untertiteln)\" width=\"1020\" height=\"574\" data-src=\"https:\/\/www.youtube.com\/embed\/vYHqMo4iLnA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2041293634\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"video video-fit mb\" style=\"padding-top:56.25%;\"><p><iframe title=\"Dutch BAKKEN - Mark Hofman zu Besuch bei Fishing Adventure Enschede!\" width=\"1020\" height=\"574\" data-src=\"https:\/\/www.youtube.com\/embed\/MK-G89zWqFA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe><\/p>\n<\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2041293634 > .col-inner {\n  padding: 0px 0px 0px 0px;\n  margin: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-823627912\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"video video-fit mb\" style=\"padding-top:56.25%;\"><p><iframe title=\"20 KILO KARPFEN UND GROSSE ST\u00d6RE ?! | BESUCH FISCHEREI ABENTEUER ENSCHEDE\" width=\"1020\" height=\"574\" data-src=\"https:\/\/www.youtube.com\/embed\/gqUKKKfsZQs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe><\/p>\n<\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-783321996\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"video video-fit mb\" style=\"padding-top:56.25%;\"><p><iframe title=\"Mega-St\u00f6re mit Fishing Adventure 2\" width=\"1020\" height=\"574\" data-src=\"https:\/\/www.youtube.com\/embed\/G0MLG-RfmLc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe><\/p>\n<\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1871523030\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"video video-fit mb\" style=\"padding-top:56.25%;\"><p><iframe title=\"Karpfenangeln auf Fishing Adventure - Maxfishing #192\" width=\"1020\" height=\"574\" data-src=\"https:\/\/www.youtube.com\/embed\/aK1jHVM4buk?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe><\/p>\n<\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-259563574\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"video video-fit mb\" style=\"padding-top:56.25%;\"><p><iframe title=\"Angeln | Jan und Dennis machen Dinge\" width=\"1020\" height=\"574\" data-src=\"https:\/\/www.youtube.com\/embed\/cQQBYFOErJw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe><\/p>\n<\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1256789935 {\n  padding-top: 10px;\n  padding-bottom: 10px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\n\t<section class=\"section\" id=\"section_1336456666\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-small\"  id=\"row-731339677\">\n\n\n\t<div id=\"col-306752665\" class=\"col medium-7 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h2>Gefangen bei Fishing Adventure<\/h2>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-306752665 > .col-inner {\n  margin: 0px 0px -25px 9px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1871853423\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"slider-wrapper relative\" id=\"slider-504671745\" >\n    <div class=\"slider slider-nav-circle slider-nav-large slider-nav-light slider-style-normal\"\n        data-flickity-options='{            \"cellAlign\": \"center\",            \"imagesLoaded\": true,            \"lazyLoad\": 1,            \"freeScroll\": false,            \"wrapAround\": true,            \"autoPlay\": 6000,            \"pauseAutoPlayOnHover\" : true,            \"prevNextButtons\": true,            \"contain\" : true,            \"adaptiveHeight\" : true,            \"dragThreshold\" : 10,            \"percentPosition\": true,            \"pageDots\": true,            \"rightToLeft\": false,            \"draggable\": true,            \"selectedAttraction\": 0.1,            \"parallax\" : 0,            \"friction\": 0.6        }'\n        >\n        \n\n<div class=\"row row-collapse align-center\"  id=\"row-297977566\">\n\n\n\t<div id=\"col-101871595\" class=\"col medium-6 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\n  <div class=\"banner has-hover\" id=\"banner-1152308790\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img decoding=\"async\" width=\"768\" height=\"459\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/07\/Beelyboat-springende-Beluga-2021-768x459.jpg?lossy=1&strip=1&webp=1\" class=\"bg attachment-medium_large size-medium_large lazyload\" alt=\"\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/07\/Beelyboat-springende-Beluga-2021-768x459.jpg?lossy=1&amp;strip=1&amp;webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/07\/Beelyboat-springende-Beluga-2021-300x179.jpg?lossy=1&amp;strip=1&amp;webp=1 300w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/07\/Beelyboat-springende-Beluga-2021-1024x611.jpg?lossy=1&amp;strip=1&amp;webp=1 1024w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/07\/Beelyboat-springende-Beluga-2021-1536x917.jpg?lossy=1&amp;strip=1&amp;webp=1 1536w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/07\/Beelyboat-springende-Beluga-2021-600x358.jpg?lossy=1&amp;strip=1&amp;webp=1 600w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/07\/Beelyboat-springende-Beluga-2021.jpg?lossy=1&amp;strip=1&amp;webp=1 1809w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/07\/Beelyboat-springende-Beluga-2021.jpg?size=204x122&amp;lossy=1&amp;strip=1&amp;webp=1 204w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/07\/Beelyboat-springende-Beluga-2021.jpg?size=408x244&amp;lossy=1&amp;strip=1&amp;webp=1 408w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 768px; --smush-placeholder-aspect-ratio: 768\/459;\" data-original-sizes=\"(max-width: 768px) 100vw, 768px\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1152308790 {\n  padding-top: 150px;\n}\n#banner-1152308790 .banner-bg img {\n  object-position: 60% 48%;\n}\n@media (min-width:550px) {\n  #banner-1152308790 {\n    padding-top: 295px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-101871595 > .col-inner {\n  padding: 0 0px 0px 0px;\n  margin: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-101871595 > .col-inner {\n    margin: 0px 0 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-177294481\" class=\"col medium-6 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n  <div class=\"banner has-hover\" id=\"banner-1447536874\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img decoding=\"async\" width=\"768\" height=\"512\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/10\/IMG-20211017-WA0009-768x512.jpg?lossy=1&strip=1&webp=1\" class=\"bg attachment-medium_large size-medium_large lazyload\" alt=\"NIEUW MEERRECORD 57,6 POND\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/10\/IMG-20211017-WA0009-768x512.jpg?lossy=1&amp;strip=1&amp;webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/10\/IMG-20211017-WA0009-300x200.jpg?lossy=1&amp;strip=1&amp;webp=1 300w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/10\/IMG-20211017-WA0009-1024x683.jpg?lossy=1&amp;strip=1&amp;webp=1 1024w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/10\/IMG-20211017-WA0009-1536x1024.jpg?lossy=1&amp;strip=1&amp;webp=1 1536w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/10\/IMG-20211017-WA0009-18x12.jpg?lossy=1&amp;strip=1&amp;webp=1 18w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/10\/IMG-20211017-WA0009-600x400.jpg?lossy=1&amp;strip=1&amp;webp=1 600w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/10\/IMG-20211017-WA0009.jpg?lossy=1&amp;strip=1&amp;webp=1 1620w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/10\/IMG-20211017-WA0009.jpg?size=204x136&amp;lossy=1&amp;strip=1&amp;webp=1 204w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/10\/IMG-20211017-WA0009.jpg?size=408x272&amp;lossy=1&amp;strip=1&amp;webp=1 408w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 768px; --smush-placeholder-aspect-ratio: 768\/512;\" data-original-sizes=\"(max-width: 768px) 100vw, 768px\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1447536874 {\n  padding-top: 150px;\n}\n#banner-1447536874 .banner-bg img {\n  object-position: 44% 33%;\n}\n@media (min-width:550px) {\n  #banner-1447536874 {\n    padding-top: 295px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-177294481 > .col-inner {\n  padding: 0px 0px 0px 0;\n  margin: 0px 0px 0px 0;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-425253358\" class=\"col medium-6 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n  <div class=\"banner has-hover\" id=\"banner-369777959\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img decoding=\"async\" width=\"768\" height=\"461\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/03\/IMG-20200730-WA0017-768x461.jpg?lossy=1&strip=1&webp=1\" class=\"bg attachment-medium_large size-medium_large lazyload\" alt=\"\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/03\/IMG-20200730-WA0017-768x461.jpg?lossy=1&amp;strip=1&amp;webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/03\/IMG-20200730-WA0017-600x360.jpg?lossy=1&amp;strip=1&amp;webp=1 600w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/03\/IMG-20200730-WA0017-300x180.jpg?lossy=1&amp;strip=1&amp;webp=1 300w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/03\/IMG-20200730-WA0017-1024x615.jpg?lossy=1&amp;strip=1&amp;webp=1 1024w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/03\/IMG-20200730-WA0017.jpg?lossy=1&amp;strip=1&amp;webp=1 1448w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/03\/IMG-20200730-WA0017.jpg?size=204x122&amp;lossy=1&amp;strip=1&amp;webp=1 204w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/03\/IMG-20200730-WA0017.jpg?size=408x245&amp;lossy=1&amp;strip=1&amp;webp=1 408w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 768px; --smush-placeholder-aspect-ratio: 768\/461;\" data-original-sizes=\"(max-width: 768px) 100vw, 768px\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-369777959 {\n  padding-top: 150px;\n}\n#banner-369777959 .banner-bg img {\n  object-position: 60% 48%;\n}\n@media (min-width:550px) {\n  #banner-369777959 {\n    padding-top: 295px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-425253358 > .col-inner {\n  padding: 0px 0px 0px 0;\n  margin: 0px 0px 0px 0;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-739983729\" class=\"col medium-6 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n  <div class=\"banner has-hover\" id=\"banner-1623326420\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img decoding=\"async\" width=\"768\" height=\"576\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/05\/2020-07-19-meerval-vanuit-de-bellyboat-768x576.jpg?lossy=1&strip=1&webp=1\" class=\"bg attachment-medium_large size-medium_large lazyload\" alt=\"\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/05\/2020-07-19-meerval-vanuit-de-bellyboat-768x576.jpg?lossy=1&amp;strip=1&amp;webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/05\/2020-07-19-meerval-vanuit-de-bellyboat-300x225.jpg?lossy=1&amp;strip=1&amp;webp=1 300w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/05\/2020-07-19-meerval-vanuit-de-bellyboat-1024x768.jpg?lossy=1&amp;strip=1&amp;webp=1 1024w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/05\/2020-07-19-meerval-vanuit-de-bellyboat-1536x1152.jpg?lossy=1&amp;strip=1&amp;webp=1 1536w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/05\/2020-07-19-meerval-vanuit-de-bellyboat-600x450.jpg?lossy=1&amp;strip=1&amp;webp=1 600w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/05\/2020-07-19-meerval-vanuit-de-bellyboat.jpg?lossy=1&amp;strip=1&amp;webp=1 1600w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/05\/2020-07-19-meerval-vanuit-de-bellyboat.jpg?size=204x153&amp;lossy=1&amp;strip=1&amp;webp=1 204w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/05\/2020-07-19-meerval-vanuit-de-bellyboat.jpg?size=408x306&amp;lossy=1&amp;strip=1&amp;webp=1 408w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 768px; --smush-placeholder-aspect-ratio: 768\/576;\" data-original-sizes=\"(max-width: 768px) 100vw, 768px\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1623326420 {\n  padding-top: 150px;\n}\n#banner-1623326420 .banner-bg img {\n  object-position: 60% 48%;\n}\n@media (min-width:550px) {\n  #banner-1623326420 {\n    padding-top: 295px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-739983729 > .col-inner {\n  padding: 0px 0px 0 0px;\n  margin: 0px 0px 0 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\n<style>\n#row-297977566 > .col > .col-inner {\n  padding: 5px 2px 0px 2px;\n}\n<\/style>\n<\/div>\n<div class=\"row row-collapse align-center\"  id=\"row-831135504\">\n\n\n\t<div id=\"col-1763693383\" class=\"col medium-6 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n  <div class=\"banner has-hover\" id=\"banner-339008404\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img decoding=\"async\" width=\"768\" height=\"432\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/07\/2021-07-10-Cluster-44-pond-768x432.jpg?lossy=1&strip=1&webp=1\" class=\"bg attachment-medium_large size-medium_large lazyload\" alt=\"\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/07\/2021-07-10-Cluster-44-pond-768x432.jpg?lossy=1&amp;strip=1&amp;webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/07\/2021-07-10-Cluster-44-pond-300x169.jpg?lossy=1&amp;strip=1&amp;webp=1 300w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/07\/2021-07-10-Cluster-44-pond-1024x576.jpg?lossy=1&amp;strip=1&amp;webp=1 1024w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/07\/2021-07-10-Cluster-44-pond-1536x864.jpg?lossy=1&amp;strip=1&amp;webp=1 1536w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/07\/2021-07-10-Cluster-44-pond-600x338.jpg?lossy=1&amp;strip=1&amp;webp=1 600w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/07\/2021-07-10-Cluster-44-pond.jpg?lossy=1&amp;strip=1&amp;webp=1 1600w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/07\/2021-07-10-Cluster-44-pond.jpg?size=204x115&amp;lossy=1&amp;strip=1&amp;webp=1 204w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/07\/2021-07-10-Cluster-44-pond.jpg?size=408x230&amp;lossy=1&amp;strip=1&amp;webp=1 408w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 768px; --smush-placeholder-aspect-ratio: 768\/432;\" data-original-sizes=\"(max-width: 768px) 100vw, 768px\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-339008404 {\n  padding-top: 150px;\n}\n#banner-339008404 .banner-bg img {\n  object-position: 58% 97%;\n}\n@media (min-width:550px) {\n  #banner-339008404 {\n    padding-top: 295px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1763693383 > .col-inner {\n  padding: 0px 0px 0px 0;\n  margin: 0px 0px 0px 0;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1129327501\" class=\"col medium-6 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n  <div class=\"banner has-hover\" id=\"banner-813047587\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img decoding=\"async\" width=\"768\" height=\"576\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/07\/IMG-20220513-2.00-meter-768x576.jpg?lossy=1&strip=1&webp=1\" class=\"bg attachment-medium_large size-medium_large lazyload\" alt=\"\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/07\/IMG-20220513-2.00-meter-768x576.jpg?lossy=1&amp;strip=1&amp;webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/07\/IMG-20220513-2.00-meter-510x383.jpg?lossy=1&amp;strip=1&amp;webp=1 510w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/07\/IMG-20220513-2.00-meter-300x225.jpg?lossy=1&amp;strip=1&amp;webp=1 300w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/07\/IMG-20220513-2.00-meter-1024x768.jpg?lossy=1&amp;strip=1&amp;webp=1 1024w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/07\/IMG-20220513-2.00-meter-1536x1152.jpg?lossy=1&amp;strip=1&amp;webp=1 1536w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/07\/IMG-20220513-2.00-meter-16x12.jpg?lossy=1&amp;strip=1&amp;webp=1 16w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/07\/IMG-20220513-2.00-meter-600x450.jpg?lossy=1&amp;strip=1&amp;webp=1 600w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/07\/IMG-20220513-2.00-meter.jpg?lossy=1&amp;strip=1&amp;webp=1 2048w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/07\/IMG-20220513-2.00-meter.jpg?size=204x153&amp;lossy=1&amp;strip=1&amp;webp=1 204w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/07\/IMG-20220513-2.00-meter.jpg?size=408x306&amp;lossy=1&amp;strip=1&amp;webp=1 408w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 768px; --smush-placeholder-aspect-ratio: 768\/576;\" data-original-sizes=\"(max-width: 768px) 100vw, 768px\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-813047587 {\n  padding-top: 150px;\n}\n#banner-813047587 .banner-bg img {\n  object-position: 58% 97%;\n}\n@media (min-width:550px) {\n  #banner-813047587 {\n    padding-top: 295px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1129327501 > .col-inner {\n  padding: 0px 0px 0px 0;\n  margin: 0px 0px 0px 0;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-213565118\" class=\"col medium-6 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n  <div class=\"banner has-hover\" id=\"banner-86443299\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img decoding=\"async\" width=\"768\" height=\"576\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/07\/IMG-20220725-236-m-768x576.jpg?lossy=1&strip=1&webp=1\" class=\"bg attachment-medium_large size-medium_large lazyload\" alt=\"\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/07\/IMG-20220725-236-m-768x576.jpg?lossy=1&amp;strip=1&amp;webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/07\/IMG-20220725-236-m-510x383.jpg?lossy=1&amp;strip=1&amp;webp=1 510w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/07\/IMG-20220725-236-m-300x225.jpg?lossy=1&amp;strip=1&amp;webp=1 300w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/07\/IMG-20220725-236-m-1024x768.jpg?lossy=1&amp;strip=1&amp;webp=1 1024w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/07\/IMG-20220725-236-m-1536x1152.jpg?lossy=1&amp;strip=1&amp;webp=1 1536w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/07\/IMG-20220725-236-m-16x12.jpg?lossy=1&amp;strip=1&amp;webp=1 16w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/07\/IMG-20220725-236-m-600x450.jpg?lossy=1&amp;strip=1&amp;webp=1 600w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/07\/IMG-20220725-236-m.jpg?lossy=1&amp;strip=1&amp;webp=1 1600w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/07\/IMG-20220725-236-m.jpg?size=204x153&amp;lossy=1&amp;strip=1&amp;webp=1 204w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/07\/IMG-20220725-236-m.jpg?size=408x306&amp;lossy=1&amp;strip=1&amp;webp=1 408w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 768px; --smush-placeholder-aspect-ratio: 768\/576;\" data-original-sizes=\"(max-width: 768px) 100vw, 768px\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-86443299 {\n  padding-top: 150px;\n}\n#banner-86443299 .banner-bg img {\n  object-position: 48% 98%;\n}\n@media (min-width:550px) {\n  #banner-86443299 {\n    padding-top: 295px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-213565118 > .col-inner {\n  padding: 0px 0px 0px 0;\n  margin: 0px 0px 0px 0;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1872193357\" class=\"col medium-6 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n  <div class=\"banner has-hover\" id=\"banner-494224265\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img decoding=\"async\" width=\"768\" height=\"513\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/07\/Vriendin-Sander-in-water-met-karper-768x513.jpg?lossy=1&strip=1&webp=1\" class=\"bg attachment-medium_large size-medium_large lazyload\" alt=\"\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/07\/Vriendin-Sander-in-water-met-karper-768x513.jpg?lossy=1&amp;strip=1&amp;webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/07\/Vriendin-Sander-in-water-met-karper-510x341.jpg?lossy=1&amp;strip=1&amp;webp=1 510w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/07\/Vriendin-Sander-in-water-met-karper-300x200.jpg?lossy=1&amp;strip=1&amp;webp=1 300w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/07\/Vriendin-Sander-in-water-met-karper-1024x684.jpg?lossy=1&amp;strip=1&amp;webp=1 1024w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/07\/Vriendin-Sander-in-water-met-karper-1536x1027.jpg?lossy=1&amp;strip=1&amp;webp=1 1536w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/07\/Vriendin-Sander-in-water-met-karper-18x12.jpg?lossy=1&amp;strip=1&amp;webp=1 18w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/07\/Vriendin-Sander-in-water-met-karper-600x401.jpg?lossy=1&amp;strip=1&amp;webp=1 600w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/07\/Vriendin-Sander-in-water-met-karper.jpg?lossy=1&amp;strip=1&amp;webp=1 1616w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/07\/Vriendin-Sander-in-water-met-karper.jpg?size=204x136&amp;lossy=1&amp;strip=1&amp;webp=1 204w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/07\/Vriendin-Sander-in-water-met-karper.jpg?size=408x273&amp;lossy=1&amp;strip=1&amp;webp=1 408w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 768px; --smush-placeholder-aspect-ratio: 768\/513;\" data-original-sizes=\"(max-width: 768px) 100vw, 768px\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-494224265 {\n  padding-top: 150px;\n}\n#banner-494224265 .banner-bg img {\n  object-position: 58% 97%;\n}\n@media (min-width:550px) {\n  #banner-494224265 {\n    padding-top: 295px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1872193357 > .col-inner {\n  padding: 0px 0px 0 0px;\n  margin: 0px 0px 0 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\n<style>\n#row-831135504 > .col > .col-inner {\n  padding: 5px 2px 0px 2px;\n}\n<\/style>\n<\/div>\n<div class=\"row row-collapse row-full-width\"  id=\"row-344190930\">\n\n\n\t<div id=\"col-1944331811\" class=\"col medium-6 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n  <div class=\"banner has-hover\" id=\"banner-435580209\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img decoding=\"async\" width=\"300\" height=\"225\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/05\/IMG-20201101-WA0009-300x225.jpg?lossy=1&strip=1&webp=1\" class=\"bg attachment-medium size-medium lazyload\" alt=\"\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/05\/IMG-20201101-WA0009-300x225.jpg?lossy=1&amp;strip=1&amp;webp=1 300w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/05\/IMG-20201101-WA0009-1024x768.jpg?lossy=1&amp;strip=1&amp;webp=1 1024w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/05\/IMG-20201101-WA0009-768x576.jpg?lossy=1&amp;strip=1&amp;webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/05\/IMG-20201101-WA0009-1536x1152.jpg?lossy=1&amp;strip=1&amp;webp=1 1536w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/05\/IMG-20201101-WA0009-600x450.jpg?lossy=1&amp;strip=1&amp;webp=1 600w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/05\/IMG-20201101-WA0009.jpg?lossy=1&amp;strip=1&amp;webp=1 1600w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/05\/IMG-20201101-WA0009.jpg?size=204x153&amp;lossy=1&amp;strip=1&amp;webp=1 204w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/225;\" data-original-sizes=\"(max-width: 300px) 100vw, 300px\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-435580209 {\n  padding-top: 150px;\n}\n#banner-435580209 .banner-bg img {\n  object-position: 47% 42%;\n}\n@media (min-width:550px) {\n  #banner-435580209 {\n    padding-top: 295px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1944331811 > .col-inner {\n  padding: 0 0px 0px 0px;\n  margin: 0px 0 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1826217224\" class=\"col medium-6 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n  <div class=\"banner has-hover\" id=\"banner-1407520087\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img decoding=\"async\" width=\"300\" height=\"225\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/03\/IMG-20200804-WA0032-002-300x225.jpg?lossy=1&strip=1&webp=1\" class=\"bg attachment-medium size-medium lazyload\" alt=\"\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/03\/IMG-20200804-WA0032-002-300x225.jpg?lossy=1&amp;strip=1&amp;webp=1 300w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/03\/IMG-20200804-WA0032-002-600x450.jpg?lossy=1&amp;strip=1&amp;webp=1 600w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/03\/IMG-20200804-WA0032-002-768x576.jpg?lossy=1&amp;strip=1&amp;webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/03\/IMG-20200804-WA0032-002.jpg?lossy=1&amp;strip=1&amp;webp=1 1024w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/03\/IMG-20200804-WA0032-002.jpg?size=204x153&amp;lossy=1&amp;strip=1&amp;webp=1 204w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/225;\" data-original-sizes=\"(max-width: 300px) 100vw, 300px\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1407520087 {\n  padding-top: 150px;\n}\n#banner-1407520087 .banner-bg img {\n  object-position: 18% 30%;\n}\n@media (min-width:550px) {\n  #banner-1407520087 {\n    padding-top: 295px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1826217224 > .col-inner {\n  padding: 0px 0px 0 0px;\n  margin: 0px 0px 0 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1857624150\" class=\"col medium-6 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n  <div class=\"banner has-hover\" id=\"banner-1273513107\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img decoding=\"async\" width=\"300\" height=\"225\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/2022-12-31-322-KG-5-300x225.jpg?lossy=1&strip=1&webp=1\" class=\"bg attachment-medium size-medium lazyload\" alt=\"NIEUW MEERRECORD KARPER\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/2022-12-31-322-KG-5-300x225.jpg?lossy=1&amp;strip=1&amp;webp=1 300w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/2022-12-31-322-KG-5-510x383.jpg?lossy=1&amp;strip=1&amp;webp=1 510w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/2022-12-31-322-KG-5-1024x768.jpg?lossy=1&amp;strip=1&amp;webp=1 1024w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/2022-12-31-322-KG-5-768x576.jpg?lossy=1&amp;strip=1&amp;webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/2022-12-31-322-KG-5-1536x1152.jpg?lossy=1&amp;strip=1&amp;webp=1 1536w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/2022-12-31-322-KG-5-16x12.jpg?lossy=1&amp;strip=1&amp;webp=1 16w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/2022-12-31-322-KG-5.jpg?lossy=1&amp;strip=1&amp;webp=1 1600w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/2022-12-31-322-KG-5.jpg?size=204x153&amp;lossy=1&amp;strip=1&amp;webp=1 204w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/225;\" data-original-sizes=\"(max-width: 300px) 100vw, 300px\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1273513107 {\n  padding-top: 150px;\n}\n#banner-1273513107 .banner-bg img {\n  object-position: 49% 57%;\n}\n@media (min-width:550px) {\n  #banner-1273513107 {\n    padding-top: 295px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1857624150 > .col-inner {\n  padding: 0px 0px 0px 0;\n  margin: 0px 0px 0px 0;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-360017264\" class=\"col medium-6 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n  <div class=\"banner has-hover\" id=\"banner-1387778551\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img decoding=\"async\" width=\"300\" height=\"250\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/05\/2020-07-19-Veit-Wilde-met-Striper-300x250.jpg?lossy=1&strip=1&webp=1\" class=\"bg attachment-medium size-medium lazyload\" alt=\"\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/05\/2020-07-19-Veit-Wilde-met-Striper-300x250.jpg?lossy=1&amp;strip=1&amp;webp=1 300w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/05\/2020-07-19-Veit-Wilde-met-Striper-768x639.jpg?lossy=1&amp;strip=1&amp;webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/05\/2020-07-19-Veit-Wilde-met-Striper-600x499.jpg?lossy=1&amp;strip=1&amp;webp=1 600w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/05\/2020-07-19-Veit-Wilde-met-Striper.jpg?lossy=1&amp;strip=1&amp;webp=1 1000w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/05\/2020-07-19-Veit-Wilde-met-Striper.jpg?size=204x170&amp;lossy=1&amp;strip=1&amp;webp=1 204w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/250;\" data-original-sizes=\"(max-width: 300px) 100vw, 300px\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1387778551 {\n  padding-top: 150px;\n}\n#banner-1387778551 .banner-bg img {\n  object-position: 49% 57%;\n}\n@media (min-width:550px) {\n  #banner-1387778551 {\n    padding-top: 295px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-360017264 > .col-inner {\n  padding: 0px 0px 0px 0;\n  margin: 0px 0px 0px 0;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\n<style>\n#row-344190930 > .col > .col-inner {\n  padding: 5px 2px 0px 2px;\n}\n<\/style>\n<\/div>\n\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1871853423 > .col-inner {\n  padding: 0px 0px 0px 0;\n  margin: 5px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\n<style>\n#row-731339677 > .col > .col-inner {\n  padding: 0 0px 0px 0px;\n}\n<\/style>\n<\/div>\n\t<div id=\"gap-1697225497\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1697225497 {\n  padding-top: 14px;\n}\n@media (min-width:550px) {\n  #gap-1697225497 {\n    padding-top: 30px;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1336456666 {\n  padding-top: 10px;\n  padding-bottom: 10px;\n  margin-bottom: -10px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section has-parallax\" id=\"section_1520550962\">\n\t\t<div class=\"section-bg fill\" data-parallax-container=\".section\" data-parallax-background data-parallax=\"-5\">\n\t\t\t<img decoding=\"async\" width=\"2048\" height=\"1536\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/04\/5-nieuwe-bigfoot-golfkarren-bij-Fishing-Adventure.jpg?lossy=1&strip=1&webp=1\" class=\"bg attachment-original size-original lazyload\" alt=\"5 nieuwe bigfoot golfkarren bij Fishing Adventure\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/04\/5-nieuwe-bigfoot-golfkarren-bij-Fishing-Adventure.jpg?lossy=1&amp;strip=1&amp;webp=1 2048w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/04\/5-nieuwe-bigfoot-golfkarren-bij-Fishing-Adventure-300x225.jpg?lossy=1&amp;strip=1&amp;webp=1 300w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/04\/5-nieuwe-bigfoot-golfkarren-bij-Fishing-Adventure-1024x768.jpg?lossy=1&amp;strip=1&amp;webp=1 1024w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/04\/5-nieuwe-bigfoot-golfkarren-bij-Fishing-Adventure-768x576.jpg?lossy=1&amp;strip=1&amp;webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/04\/5-nieuwe-bigfoot-golfkarren-bij-Fishing-Adventure-1536x1152.jpg?lossy=1&amp;strip=1&amp;webp=1 1536w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/04\/5-nieuwe-bigfoot-golfkarren-bij-Fishing-Adventure-16x12.jpg?lossy=1&amp;strip=1&amp;webp=1 16w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/04\/5-nieuwe-bigfoot-golfkarren-bij-Fishing-Adventure-510x383.jpg?lossy=1&amp;strip=1&amp;webp=1 510w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/04\/5-nieuwe-bigfoot-golfkarren-bij-Fishing-Adventure.jpg?size=204x153&amp;lossy=1&amp;strip=1&amp;webp=1 204w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/04\/5-nieuwe-bigfoot-golfkarren-bij-Fishing-Adventure.jpg?size=408x306&amp;lossy=1&amp;strip=1&amp;webp=1 408w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/04\/5-nieuwe-bigfoot-golfkarren-bij-Fishing-Adventure.jpg?size=612x459&amp;lossy=1&amp;strip=1&amp;webp=1 612w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 2048px; --smush-placeholder-aspect-ratio: 2048\/1536;\" data-original-sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t<div class=\"section-bg-overlay absolute fill\"><\/div>\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:0px 0px 0px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse row-full-width align-equal\"  id=\"row-249605017\">\n\n\n\t<div id=\"col-604052020\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-1196547675\" class=\"text\">\n\t\t\n\n<h2>Erleben Sie unsere neuen Golfcarts<\/h2>\n\t\t\n<style>\n#text-1196547675 {\n  font-size: 1.6rem;\n  text-align: center;\n  color: rgb(255, 255, 255);\n}\n#text-1196547675 > * {\n  color: rgb(255, 255, 255);\n}\n@media (min-width:550px) {\n  #text-1196547675 {\n    font-size: 1.3rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1642181567\" class=\"text\">\n\t\t\n\n<p>Bereit f\u00fcr ein Abenteuer? Bei Fishing Adventure, dem gr\u00f6\u00dften Lohngew\u00e4sser der Niederlande, fahren Sie stilvoll in unseren luxuri\u00f6sen Golfwagen. Durch den Wald, am Wasser entlang und direkt zu Ihrem Angelplatz - schnell, reibungslos und mit einer guten Portion Spa\u00df. Perfekt f\u00fcr Gruppen, die keine Lust auf Schlepperei haben, aber trotzdem alles erleben wollen. Reiten, angeln, entspannen. Alles in Ihrem Tempo.<\/p>\n\t\t\n<style>\n#text-1642181567 {\n  font-size: 1rem;\n  text-align: center;\n  color: rgb(255, 255, 255);\n}\n#text-1642181567 > * {\n  color: rgb(255, 255, 255);\n}\n@media (min-width:550px) {\n  #text-1642181567 {\n    font-size: 1.3rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"https:\/\/www.fishingadventure.nl\/de\/golfkarren\/\" class=\"button white\">\n\t\t<span>Unsere Golfwagen<\/span>\n\t<\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-604052020 > .col-inner {\n  padding: 0px 15px 0px 15px;\n}\n@media (min-width:550px) {\n  #col-604052020 > .col-inner {\n    padding: 149px 35px 152px 35px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1520550962 {\n  padding-top: 52px;\n  padding-bottom: 52px;\n}\n#section_1520550962 .section-bg-overlay {\n  background-color: rgba(0, 0, 0, 0.448);\n}\n#section_1520550962 .section-bg img {\n  object-position: 46% 75%;\n}\n@media (min-width:550px) {\n  #section_1520550962 {\n    padding-top: 45px;\n    padding-bottom: 45px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-1806314435\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1806314435 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t<section class=\"section\" id=\"section_29585935\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-small\"  id=\"row-1522695611\">\n\n\n\t<div id=\"col-404466894\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h2>Infos zum Angeln am Abenteuersee<\/h2>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-404466894 > .col-inner {\n  padding: 0px 0px 0px 0px;\n  margin: 0px 0px -16px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1632813589\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-color:rgb(255, 255, 255);border-width:0px 0 0px 0px;margin:0 0px 0px 0px;\">\n\t<\/div>\n\t\t\t\n\n\n  <div class=\"banner has-hover bg-overlay-remove-50\" id=\"banner-956877516\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img decoding=\"async\" width=\"768\" height=\"576\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/03\/IMG-20201105-Rbv-Vanaf-zuidwest-hoek-768x576.jpg?lossy=1&strip=1&webp=1\" class=\"bg attachment-medium_large size-medium_large lazyload\" alt=\"\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/03\/IMG-20201105-Rbv-Vanaf-zuidwest-hoek-768x576.jpg?lossy=1&amp;strip=1&amp;webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/03\/IMG-20201105-Rbv-Vanaf-zuidwest-hoek-600x450.jpg?lossy=1&amp;strip=1&amp;webp=1 600w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/03\/IMG-20201105-Rbv-Vanaf-zuidwest-hoek-300x225.jpg?lossy=1&amp;strip=1&amp;webp=1 300w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/03\/IMG-20201105-Rbv-Vanaf-zuidwest-hoek-1024x768.jpg?lossy=1&amp;strip=1&amp;webp=1 1024w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/03\/IMG-20201105-Rbv-Vanaf-zuidwest-hoek-1536x1152.jpg?lossy=1&amp;strip=1&amp;webp=1 1536w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/03\/IMG-20201105-Rbv-Vanaf-zuidwest-hoek.jpg?lossy=1&amp;strip=1&amp;webp=1 1600w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/03\/IMG-20201105-Rbv-Vanaf-zuidwest-hoek.jpg?size=204x153&amp;lossy=1&amp;strip=1&amp;webp=1 204w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/03\/IMG-20201105-Rbv-Vanaf-zuidwest-hoek.jpg?size=408x306&amp;lossy=1&amp;strip=1&amp;webp=1 408w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 768px; --smush-placeholder-aspect-ratio: 768\/576;\" data-original-sizes=\"(max-width: 768px) 100vw, 768px\" \/>                        <div class=\"overlay\"><\/div>            \n\t<div class=\"is-border\"\n\t\tstyle=\"border-color:rgb(255, 255, 255);border-width:0 0px 0px 0px;margin:0 0px 0px 0px;\">\n\t<\/div>\n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <a class=\"fill\" href=\"https:\/\/www.fishingadventure.nl\/de\/boek-een-stek-bij-fishing-adventure-lake\/\" target=\"_blank\" rel=\"noopener\"><div class=\"fill banner-link\"><\/div><\/a>            \n\n   <div id=\"text-box-1778633640\" class=\"text-box banner-layer x50 md-x100 lg-x50 y30 md-y25 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark text-shadow-5\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n<p><a href=\"https:\/\/bookings.fishingadventure.nl\/\"><\/p>\n<h3 class=\"uppercase\"><strong>Angelplatz buchen<\/strong><\/h3>\n<p><strong>buchen Sie direkt einen Angelplatz bei Fishing Adventure via unserem Buchungssystem.<\/strong><\/p>\n<p><\/a><\/p>\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1778633640 {\n  width: 100%;\n}\n#text-box-1778633640 .text-box-content {\n  font-size: 130%;\n}\n@media (min-width:850px) {\n  #text-box-1778633640 {\n    width: 73%;\n  }\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-956877516 {\n  padding-top: 220px;\n}\n#banner-956877516 .overlay {\n  background-color: rgba(0, 0, 0, 0.273);\n}\n#banner-956877516 .banner-bg img {\n  object-position: 36% 52%;\n}\n@media (min-width:550px) {\n  #banner-956877516 {\n    padding-top: 334px;\n  }\n  #banner-956877516 .overlay {\n    background-color: rgba(0, 0, 0, 0.233);\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1632813589 > .col-inner {\n  padding: 0px 2px 0px 0px;\n  margin: 0px 0px 0px 0px;\n}\n@media (min-width:850px) {\n  #col-1632813589 > .col-inner {\n    padding: 0px 2px 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1383135714\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-color:rgb(255, 255, 255);border-width:0px 0 0px 0px;\">\n\t<\/div>\n\t\t\t\n\n\n  <div class=\"banner has-hover bg-overlay-remove-50\" id=\"banner-1952652086\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img decoding=\"async\" width=\"768\" height=\"432\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2019\/02\/Fishing-Adventure-Rutbekerveld-768x432.jpg?lossy=1&strip=1&webp=1\" class=\"bg attachment-medium_large size-medium_large lazyload\" alt=\"\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2019\/02\/Fishing-Adventure-Rutbekerveld-768x432.jpg?lossy=1&amp;strip=1&amp;webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2019\/02\/Fishing-Adventure-Rutbekerveld-600x338.jpg?lossy=1&amp;strip=1&amp;webp=1 600w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2019\/02\/Fishing-Adventure-Rutbekerveld-300x169.jpg?lossy=1&amp;strip=1&amp;webp=1 300w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2019\/02\/Fishing-Adventure-Rutbekerveld-1024x576.jpg?lossy=1&amp;strip=1&amp;webp=1 1024w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2019\/02\/Fishing-Adventure-Rutbekerveld-1536x864.jpg?lossy=1&amp;strip=1&amp;webp=1 1536w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2019\/02\/Fishing-Adventure-Rutbekerveld.jpg?lossy=1&amp;strip=1&amp;webp=1 1920w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2019\/02\/Fishing-Adventure-Rutbekerveld.jpg?size=204x115&amp;lossy=1&amp;strip=1&amp;webp=1 204w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2019\/02\/Fishing-Adventure-Rutbekerveld.jpg?size=408x230&amp;lossy=1&amp;strip=1&amp;webp=1 408w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 768px; --smush-placeholder-aspect-ratio: 768\/432;\" data-original-sizes=\"(max-width: 768px) 100vw, 768px\" \/>                        <div class=\"overlay\"><\/div>            \n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:0px 0px 0px 2px;\">\n\t<\/div>\n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <a class=\"fill\" href=\"https:\/\/tour.fishingadventure.nl\/\" target=\"_blank\" rel=\"noopener\"><div class=\"fill banner-link\"><\/div><\/a>            \n\n   <div id=\"text-box-428319546\" class=\"text-box banner-layer x90 md-x90 lg-x90 y50 md-y10 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark text-shadow-5\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n<p><a href=\"https:\/\/www.fishingadventure.nl\/de\/virtuele-tour\/\"><\/p>\n<h3 class=\"uppercase\"><strong>Abenteuer See Tour<\/strong><\/h3>\n<p><strong>Sehen Sie sich hier die spektakul\u00e4ren Bilder unserer virtuellen Tour an. Machen Sie sich ein Bild vom Gew\u00e4sser und den beiden Angelh\u00fctten.<br \/>\nVerschaffen Sie sich einen \u00dcberblick \u00fcber das Wasser und die beiden Fischerh\u00fctten.<\/strong><\/p>\n<p><\/a><\/p>\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-428319546 {\n  width: 80%;\n}\n#text-box-428319546 .text-box-content {\n  font-size: 130%;\n}\n@media (min-width:550px) {\n  #text-box-428319546 {\n    width: 96%;\n  }\n}\n@media (min-width:850px) {\n  #text-box-428319546 {\n    width: 75%;\n  }\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1952652086 {\n  padding-top: 220px;\n}\n#banner-1952652086 .overlay {\n  background-color: rgba(0, 0, 0, 0.43);\n}\n#banner-1952652086 .banner-bg img {\n  object-position: 51% 35%;\n}\n@media (min-width:550px) {\n  #banner-1952652086 {\n    padding-top: 334px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1383135714 > .col-inner {\n  padding: 0px 0px 0px 2px;\n  margin: 3px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1383135714 > .col-inner {\n    margin: 0px 00px 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_29585935 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n@media (min-width:850px) {\n  #section_29585935 {\n    padding-top: 15px;\n    padding-bottom: 15px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1254331\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-small\"  id=\"row-1035397378\">\n\n\n\t<div id=\"col-711935162\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h2>Letzte Nachrichten von Fishing Adventure<\/h2>\n\n  \n    <div class=\"row large-columns-4 medium-columns-2 small-columns-1 row-xsmall slider row-slider slider-nav-reveal slider-nav-push\"  data-flickity-options='{&quot;imagesLoaded&quot;: true, &quot;groupCells&quot;: &quot;100%&quot;, &quot;dragThreshold&quot; : 5, &quot;cellAlign&quot;: &quot;left&quot;,&quot;wrapAround&quot;: true,&quot;prevNextButtons&quot;: true,&quot;percentPosition&quot;: true,&quot;pageDots&quot;: false, &quot;rightToLeft&quot;: false, &quot;autoPlay&quot; : false}' >\n\n  <div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:65%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.fishingadventure.nl\/de\/bellyfiction-2026-het-ultieme-bellyboat-kayak-roofvistoernooi-bij-fishing-adventure\/\" class=\"plain\" aria-label=\"Bellyfiction 2026 - Das ultimative Bellyboat- &amp; Kajak-R\u00e4uber-Turnier bei Fishing Adventure\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"200\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2026\/02\/Bellyfiction-Promo-Image-Fishing-Adventure-300x200.jpg?lossy=1&strip=1&webp=1\" class=\"attachment-medium size-medium wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2026\/02\/Bellyfiction-Promo-Image-Fishing-Adventure-300x200.jpg?lossy=1&strip=1&webp=1 300w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2026\/02\/Bellyfiction-Promo-Image-Fishing-Adventure-1024x683.jpg?lossy=1&strip=1&webp=1 1024w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2026\/02\/Bellyfiction-Promo-Image-Fishing-Adventure-768x512.jpg?lossy=1&strip=1&webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2026\/02\/Bellyfiction-Promo-Image-Fishing-Adventure-18x12.jpg?lossy=1&strip=1&webp=1 18w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2026\/02\/Bellyfiction-Promo-Image-Fishing-Adventure-510x340.jpg?lossy=1&strip=1&webp=1 510w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2026\/02\/Bellyfiction-Promo-Image-Fishing-Adventure.jpg?lossy=1&strip=1&webp=1 1536w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2026\/02\/Bellyfiction-Promo-Image-Fishing-Adventure.jpg?size=204x136&lossy=1&strip=1&webp=1 204w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/200;\" data-original-sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0, 0, 0, 0.448)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center is-small\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.fishingadventure.nl\/de\/bellyfiction-2026-het-ultieme-bellyboat-kayak-roofvistoernooi-bij-fishing-adventure\/\" class=\"plain\">Bellyfiction 2026 - Das ultimative Bellyboat- &amp; Kajak-R\u00e4uber-Turnier bei Fishing Adventure<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">15<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Feb.<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:65%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.fishingadventure.nl\/de\/voorbereiding-bellyfiction-2026\/\" class=\"plain\" aria-label=\"Vorbereitung von Bellyfiction 2026\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"200\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2026\/02\/Voorbereiding-Bellyfiction-2026-300x200.jpg?lossy=1&strip=1&webp=1\" class=\"attachment-medium size-medium wp-post-image lazyload\" alt=\"Voorbereiding Bellyfiction 2026\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2026\/02\/Voorbereiding-Bellyfiction-2026-300x200.jpg?lossy=1&strip=1&webp=1 300w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2026\/02\/Voorbereiding-Bellyfiction-2026-1024x683.jpg?lossy=1&strip=1&webp=1 1024w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2026\/02\/Voorbereiding-Bellyfiction-2026-768x512.jpg?lossy=1&strip=1&webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2026\/02\/Voorbereiding-Bellyfiction-2026-18x12.jpg?lossy=1&strip=1&webp=1 18w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2026\/02\/Voorbereiding-Bellyfiction-2026-510x340.jpg?lossy=1&strip=1&webp=1 510w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2026\/02\/Voorbereiding-Bellyfiction-2026.jpg?lossy=1&strip=1&webp=1 1536w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2026\/02\/Voorbereiding-Bellyfiction-2026.jpg?size=204x136&lossy=1&strip=1&webp=1 204w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/200;\" data-original-sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0, 0, 0, 0.448)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center is-small\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.fishingadventure.nl\/de\/voorbereiding-bellyfiction-2026\/\" class=\"plain\">Vorbereitung von Bellyfiction 2026<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">12<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Feb.<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:65%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.fishingadventure.nl\/de\/het-grootste-betaalwater-van-nederland-2-hectare-groter\/\" class=\"plain\" aria-label=\"Das gr\u00f6\u00dfte Bezahlwasser der Niederlande 2 Hektar gr\u00f6\u00dfer\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"169\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/12\/Het-grootste-betaalwater-van-Nederland-weer-2-hectare-groter-300x169.jpg?lossy=1&strip=1&webp=1\" class=\"attachment-medium size-medium wp-post-image lazyload\" alt=\"Het grootste betaalwater van Nederland weer 2 hectare groter\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/12\/Het-grootste-betaalwater-van-Nederland-weer-2-hectare-groter-300x169.jpg?lossy=1&strip=1&webp=1 300w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/12\/Het-grootste-betaalwater-van-Nederland-weer-2-hectare-groter-1024x576.jpg?lossy=1&strip=1&webp=1 1024w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/12\/Het-grootste-betaalwater-van-Nederland-weer-2-hectare-groter-768x432.jpg?lossy=1&strip=1&webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/12\/Het-grootste-betaalwater-van-Nederland-weer-2-hectare-groter-1536x864.jpg?lossy=1&strip=1&webp=1 1536w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/12\/Het-grootste-betaalwater-van-Nederland-weer-2-hectare-groter-18x10.jpg?lossy=1&strip=1&webp=1 18w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/12\/Het-grootste-betaalwater-van-Nederland-weer-2-hectare-groter-510x287.jpg?lossy=1&strip=1&webp=1 510w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/12\/Het-grootste-betaalwater-van-Nederland-weer-2-hectare-groter.jpg?lossy=1&strip=1&webp=1 2048w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/12\/Het-grootste-betaalwater-van-Nederland-weer-2-hectare-groter.jpg?size=204x115&lossy=1&strip=1&webp=1 204w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/169;\" data-original-sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0, 0, 0, 0.448)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center is-small\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.fishingadventure.nl\/de\/het-grootste-betaalwater-van-nederland-2-hectare-groter\/\" class=\"plain\">Das gr\u00f6\u00dfte Bezahlwasser der Niederlande 2 Hektar gr\u00f6\u00dfer<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">05<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Dez.<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:65%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.fishingadventure.nl\/de\/fa-baits-bundel-deals\/\" class=\"plain\" aria-label=\"FA Baits Bundle-Angebote\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"209\" height=\"300\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/12\/Bundel-Deals-2-zakken-1kg-Readymade-Boilies-2-potjes-Flavoured-Popups-209x300.jpg?lossy=1&strip=1&webp=1\" class=\"attachment-medium size-medium wp-post-image lazyload\" alt=\"FA Baits Bundel Deals\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/12\/Bundel-Deals-2-zakken-1kg-Readymade-Boilies-2-potjes-Flavoured-Popups-209x300.jpg?lossy=1&strip=1&webp=1 209w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/12\/Bundel-Deals-2-zakken-1kg-Readymade-Boilies-2-potjes-Flavoured-Popups-713x1024.jpg?lossy=1&strip=1&webp=1 713w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/12\/Bundel-Deals-2-zakken-1kg-Readymade-Boilies-2-potjes-Flavoured-Popups-768x1104.jpg?lossy=1&strip=1&webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/12\/Bundel-Deals-2-zakken-1kg-Readymade-Boilies-2-potjes-Flavoured-Popups-1069x1536.jpg?lossy=1&strip=1&webp=1 1069w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/12\/Bundel-Deals-2-zakken-1kg-Readymade-Boilies-2-potjes-Flavoured-Popups-8x12.jpg?lossy=1&strip=1&webp=1 8w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/12\/Bundel-Deals-2-zakken-1kg-Readymade-Boilies-2-potjes-Flavoured-Popups-510x733.jpg?lossy=1&strip=1&webp=1 510w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/12\/Bundel-Deals-2-zakken-1kg-Readymade-Boilies-2-potjes-Flavoured-Popups.jpg?lossy=1&strip=1&webp=1 1425w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 209px; --smush-placeholder-aspect-ratio: 209\/300;\" data-original-sizes=\"(max-width: 209px) 100vw, 209px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0, 0, 0, 0.448)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center is-small\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.fishingadventure.nl\/de\/fa-baits-bundel-deals\/\" class=\"plain\">FA Baits Bundle-Angebote<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">05<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Dez.<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:65%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.fishingadventure.nl\/de\/fa-baits-boilies-pop-ups-particles\/\" class=\"plain\" aria-label=\"FA-K\u00f6der: Boilies, Pop-Ups &amp; Partikel\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/11\/Logo-FA-Baits-300x225.jpg?lossy=1&strip=1&webp=1\" class=\"attachment-medium size-medium wp-post-image lazyload\" alt=\"Logo FA Baits\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/11\/Logo-FA-Baits-300x225.jpg?lossy=1&strip=1&webp=1 300w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/11\/Logo-FA-Baits-768x576.jpg?lossy=1&strip=1&webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/11\/Logo-FA-Baits-16x12.jpg?lossy=1&strip=1&webp=1 16w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/11\/Logo-FA-Baits-510x383.jpg?lossy=1&strip=1&webp=1 510w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/11\/Logo-FA-Baits.jpg?lossy=1&strip=1&webp=1 1024w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/11\/Logo-FA-Baits.jpg?size=204x153&lossy=1&strip=1&webp=1 204w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/225;\" data-original-sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0, 0, 0, 0.448)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center is-small\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.fishingadventure.nl\/de\/fa-baits-boilies-pop-ups-particles\/\" class=\"plain\">FA Baits: Boilies, Pop-Ups &amp; Particles<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">29<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Nov.<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:65%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.fishingadventure.nl\/de\/nieuwe-hongaarse-karpers-uitgezet-op-de-lake\/\" class=\"plain\" aria-label=\"Neue ungarische Karpfen im See ausgesetzt\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"199\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/11\/Hongaarse-Karpers-uitgezet2-300x199.jpg?lossy=1&strip=1&webp=1\" class=\"attachment-medium size-medium wp-post-image lazyload\" alt=\"Hongaarse Karpers uitgezet2\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/11\/Hongaarse-Karpers-uitgezet2-300x199.jpg?lossy=1&strip=1&webp=1 300w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/11\/Hongaarse-Karpers-uitgezet2-18x12.jpg?lossy=1&strip=1&webp=1 18w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/11\/Hongaarse-Karpers-uitgezet2-510x339.jpg?lossy=1&strip=1&webp=1 510w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/11\/Hongaarse-Karpers-uitgezet2.jpg?lossy=1&strip=1&webp=1 590w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/11\/Hongaarse-Karpers-uitgezet2.jpg?size=204x135&lossy=1&strip=1&webp=1 204w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/199;\" data-original-sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0, 0, 0, 0.448)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center is-small\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.fishingadventure.nl\/de\/nieuwe-hongaarse-karpers-uitgezet-op-de-lake\/\" class=\"plain\">Neue ungarische Karpfen im See ausgesetzt<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">28<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Nov.<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:65%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.fishingadventure.nl\/de\/14-nieuwe-hongaarse-karpers-uitgezet-op-de-lagoon\/\" class=\"plain\" aria-label=\"14 neue ungarische Karpfen in der Lagune ausgesetzt\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/11\/Nieuwe-Hongaarse-Karpers-uitgezet-op-de-Lagoon-Zilverkarper-300x225.jpg?lossy=1&strip=1&webp=1\" class=\"attachment-medium size-medium wp-post-image lazyload\" alt=\"Nieuwe Hongaarse Karpers uitgezet op de Lagoon - Zilverkarper\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/11\/Nieuwe-Hongaarse-Karpers-uitgezet-op-de-Lagoon-Zilverkarper-300x225.jpg?lossy=1&strip=1&webp=1 300w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/11\/Nieuwe-Hongaarse-Karpers-uitgezet-op-de-Lagoon-Zilverkarper-1024x768.jpg?lossy=1&strip=1&webp=1 1024w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/11\/Nieuwe-Hongaarse-Karpers-uitgezet-op-de-Lagoon-Zilverkarper-768x576.jpg?lossy=1&strip=1&webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/11\/Nieuwe-Hongaarse-Karpers-uitgezet-op-de-Lagoon-Zilverkarper-1536x1152.jpg?lossy=1&strip=1&webp=1 1536w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/11\/Nieuwe-Hongaarse-Karpers-uitgezet-op-de-Lagoon-Zilverkarper-16x12.jpg?lossy=1&strip=1&webp=1 16w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/11\/Nieuwe-Hongaarse-Karpers-uitgezet-op-de-Lagoon-Zilverkarper-510x383.jpg?lossy=1&strip=1&webp=1 510w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/11\/Nieuwe-Hongaarse-Karpers-uitgezet-op-de-Lagoon-Zilverkarper.jpg?lossy=1&strip=1&webp=1 2000w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/11\/Nieuwe-Hongaarse-Karpers-uitgezet-op-de-Lagoon-Zilverkarper.jpg?size=204x153&lossy=1&strip=1&webp=1 204w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/225;\" data-original-sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0, 0, 0, 0.448)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center is-small\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.fishingadventure.nl\/de\/14-nieuwe-hongaarse-karpers-uitgezet-op-de-lagoon\/\" class=\"plain\">14 neue ungarische Karpfen in der Lagune ausgesetzt<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">22<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Nov.<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:65%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.fishingadventure.nl\/de\/nieuw-meerrecord-steur-2-54\/\" class=\"plain\" aria-label=\"Neuer See-Rekord St\u00f6r 2.54\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/09\/20250922-stek-13-2.54-nieuw-meerrecord-300x225.jpg?lossy=1&strip=1&webp=1\" class=\"attachment-medium size-medium wp-post-image lazyload\" alt=\"Nieuw Meerrecord Steur 2.54\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/09\/20250922-stek-13-2.54-nieuw-meerrecord-300x225.jpg?lossy=1&strip=1&webp=1 300w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/09\/20250922-stek-13-2.54-nieuw-meerrecord-1024x768.jpg?lossy=1&strip=1&webp=1 1024w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/09\/20250922-stek-13-2.54-nieuw-meerrecord-768x576.jpg?lossy=1&strip=1&webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/09\/20250922-stek-13-2.54-nieuw-meerrecord-1536x1152.jpg?lossy=1&strip=1&webp=1 1536w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/09\/20250922-stek-13-2.54-nieuw-meerrecord-16x12.jpg?lossy=1&strip=1&webp=1 16w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/09\/20250922-stek-13-2.54-nieuw-meerrecord-510x383.jpg?lossy=1&strip=1&webp=1 510w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/09\/20250922-stek-13-2.54-nieuw-meerrecord.jpg?lossy=1&strip=1&webp=1 1600w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/09\/20250922-stek-13-2.54-nieuw-meerrecord.jpg?size=204x153&lossy=1&strip=1&webp=1 204w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/225;\" data-original-sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0, 0, 0, 0.448)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center is-small\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.fishingadventure.nl\/de\/nieuw-meerrecord-steur-2-54\/\" class=\"plain\">Neuer See-Rekord St\u00f6r 2.54<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">25<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Sep.<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:65%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.fishingadventure.nl\/de\/nieuw-meerrecord-steur-van-2-52m-bij-fishing-adventure\/\" class=\"plain\" aria-label=\"Neuer See-Rekordst\u00f6r von 2,52 m bei Fishing Adventure!\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/04\/Nieuw-meerrecord-Steur-Bij-Fishing-Adventure-300x225.jpg?lossy=1&strip=1&webp=1\" class=\"attachment-medium size-medium wp-post-image lazyload\" alt=\"Nieuw Meerrecord Steur van 2.52M bij Fishing Adventure!\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/04\/Nieuw-meerrecord-Steur-Bij-Fishing-Adventure-300x225.jpg?lossy=1&strip=1&webp=1 300w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/04\/Nieuw-meerrecord-Steur-Bij-Fishing-Adventure-1024x768.jpg?lossy=1&strip=1&webp=1 1024w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/04\/Nieuw-meerrecord-Steur-Bij-Fishing-Adventure-768x576.jpg?lossy=1&strip=1&webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/04\/Nieuw-meerrecord-Steur-Bij-Fishing-Adventure-1536x1152.jpg?lossy=1&strip=1&webp=1 1536w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/04\/Nieuw-meerrecord-Steur-Bij-Fishing-Adventure-16x12.jpg?lossy=1&strip=1&webp=1 16w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/04\/Nieuw-meerrecord-Steur-Bij-Fishing-Adventure-510x383.jpg?lossy=1&strip=1&webp=1 510w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/04\/Nieuw-meerrecord-Steur-Bij-Fishing-Adventure.jpg?lossy=1&strip=1&webp=1 2048w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/04\/Nieuw-meerrecord-Steur-Bij-Fishing-Adventure.jpg?size=204x153&lossy=1&strip=1&webp=1 204w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/225;\" data-original-sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0, 0, 0, 0.448)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center is-small\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.fishingadventure.nl\/de\/nieuw-meerrecord-steur-van-2-52m-bij-fishing-adventure\/\" class=\"plain\">Neuer See-Rekordst\u00f6r von 2,52 m bei Fishing Adventure!<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">15<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Apr.<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:65%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.fishingadventure.nl\/de\/5-nieuwe-bigfoot-golfkarren-bij-fishing-adventure\/\" class=\"plain\" aria-label=\"5 neue Bigfoot-Golfwagen bei Fishing Adventure\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/04\/5-nieuwe-bigfoot-golfkarren-bij-Fishing-Adventure-300x225.jpg?lossy=1&strip=1&webp=1\" class=\"attachment-medium size-medium wp-post-image lazyload\" alt=\"5 nieuwe bigfoot golfkarren bij Fishing Adventure\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/04\/5-nieuwe-bigfoot-golfkarren-bij-Fishing-Adventure-300x225.jpg?lossy=1&strip=1&webp=1 300w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/04\/5-nieuwe-bigfoot-golfkarren-bij-Fishing-Adventure-1024x768.jpg?lossy=1&strip=1&webp=1 1024w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/04\/5-nieuwe-bigfoot-golfkarren-bij-Fishing-Adventure-768x576.jpg?lossy=1&strip=1&webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/04\/5-nieuwe-bigfoot-golfkarren-bij-Fishing-Adventure-1536x1152.jpg?lossy=1&strip=1&webp=1 1536w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/04\/5-nieuwe-bigfoot-golfkarren-bij-Fishing-Adventure-16x12.jpg?lossy=1&strip=1&webp=1 16w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/04\/5-nieuwe-bigfoot-golfkarren-bij-Fishing-Adventure-510x383.jpg?lossy=1&strip=1&webp=1 510w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/04\/5-nieuwe-bigfoot-golfkarren-bij-Fishing-Adventure.jpg?lossy=1&strip=1&webp=1 2048w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2025\/04\/5-nieuwe-bigfoot-golfkarren-bij-Fishing-Adventure.jpg?size=204x153&lossy=1&strip=1&webp=1 204w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/225;\" data-original-sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0, 0, 0, 0.448)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center is-small\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.fishingadventure.nl\/de\/5-nieuwe-bigfoot-golfkarren-bij-fishing-adventure\/\" class=\"plain\">5 neue Bigfoot-Golfwagen bei Fishing Adventure<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">10<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Apr.<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:65%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.fishingadventure.nl\/de\/nieuw-meerrecord-karper-322-kg\/\" class=\"plain\" aria-label=\"NEUER SEEREKORD KARPFEN 32,2 KG\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/2022-12-31-322-KG-5-300x225.jpg?lossy=1&strip=1&webp=1\" class=\"attachment-medium size-medium wp-post-image lazyload\" alt=\"NIEUW MEERRECORD KARPER\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/2022-12-31-322-KG-5-300x225.jpg?lossy=1&strip=1&webp=1 300w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/2022-12-31-322-KG-5-510x383.jpg?lossy=1&strip=1&webp=1 510w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/2022-12-31-322-KG-5-1024x768.jpg?lossy=1&strip=1&webp=1 1024w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/2022-12-31-322-KG-5-768x576.jpg?lossy=1&strip=1&webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/2022-12-31-322-KG-5-1536x1152.jpg?lossy=1&strip=1&webp=1 1536w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/2022-12-31-322-KG-5-16x12.jpg?lossy=1&strip=1&webp=1 16w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/2022-12-31-322-KG-5.jpg?lossy=1&strip=1&webp=1 1600w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2023\/01\/2022-12-31-322-KG-5.jpg?size=204x153&lossy=1&strip=1&webp=1 204w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/225;\" data-original-sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0, 0, 0, 0.448)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center is-small\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.fishingadventure.nl\/de\/nieuw-meerrecord-karper-322-kg\/\" class=\"plain\">NEUER SEEREKORD KARPFEN 32,2 KG<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">01<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Jan.<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:65%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.fishingadventure.nl\/de\/1-11-22-nieuw-meer-record-steur-2-45-meter\/\" class=\"plain\" aria-label=\"1-11-22 Neuer Seerekord f\u00fcr St\u00f6re 2,45 Meter\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/11\/IMG-20221101-2.45-meter-300x225.jpg?lossy=1&strip=1&webp=1\" class=\"attachment-medium size-medium wp-post-image lazyload\" alt=\"1-11-22 Nieuw meer-record steur 2.45 meter\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/11\/IMG-20221101-2.45-meter-300x225.jpg?lossy=1&strip=1&webp=1 300w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/11\/IMG-20221101-2.45-meter-510x383.jpg?lossy=1&strip=1&webp=1 510w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/11\/IMG-20221101-2.45-meter-1024x768.jpg?lossy=1&strip=1&webp=1 1024w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/11\/IMG-20221101-2.45-meter-768x576.jpg?lossy=1&strip=1&webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/11\/IMG-20221101-2.45-meter-1536x1152.jpg?lossy=1&strip=1&webp=1 1536w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/11\/IMG-20221101-2.45-meter-16x12.jpg?lossy=1&strip=1&webp=1 16w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/11\/IMG-20221101-2.45-meter.jpg?lossy=1&strip=1&webp=1 1600w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/11\/IMG-20221101-2.45-meter.jpg?size=204x153&lossy=1&strip=1&webp=1 204w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/225;\" data-original-sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0, 0, 0, 0.448)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center is-small\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.fishingadventure.nl\/de\/1-11-22-nieuw-meer-record-steur-2-45-meter\/\" class=\"plain\">1-11-22 Neuer Seerekord f\u00fcr St\u00f6re 2,45 Meter<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">01<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Nov.<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:65%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.fishingadventure.nl\/de\/nieuw-meerrecord-karper-bij-fishing-adventure\/\" class=\"plain\" aria-label=\"NEUER SEE-REKORDKARPFEN BEI FISHING ADVENTURE 29,1 KG\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/07\/2022-07-02-29-1-KG-582-pond-300x300.jpg?lossy=1&strip=1&webp=1\" class=\"attachment-medium size-medium wp-post-image lazyload\" alt=\"NIEUW MEERRECORD KARPER BIJ FISHING ADVENTURE 29,1 KG\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/07\/2022-07-02-29-1-KG-582-pond-300x300.jpg?lossy=1&strip=1&webp=1 300w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/07\/2022-07-02-29-1-KG-582-pond-100x100.jpg?lossy=1&strip=1&webp=1 100w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/07\/2022-07-02-29-1-KG-582-pond-510x510.jpg?lossy=1&strip=1&webp=1 510w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/07\/2022-07-02-29-1-KG-582-pond-1024x1024.jpg?lossy=1&strip=1&webp=1 1024w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/07\/2022-07-02-29-1-KG-582-pond-150x150.jpg?lossy=1&strip=1&webp=1 150w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/07\/2022-07-02-29-1-KG-582-pond-768x768.jpg?lossy=1&strip=1&webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/07\/2022-07-02-29-1-KG-582-pond-12x12.jpg?lossy=1&strip=1&webp=1 12w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/07\/2022-07-02-29-1-KG-582-pond-600x600.jpg?lossy=1&strip=1&webp=1 600w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/07\/2022-07-02-29-1-KG-582-pond.jpg?lossy=1&strip=1&webp=1 1242w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/07\/2022-07-02-29-1-KG-582-pond.jpg?size=204x204&lossy=1&strip=1&webp=1 204w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" data-original-sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0, 0, 0, 0.448)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center is-small\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.fishingadventure.nl\/de\/nieuw-meerrecord-karper-bij-fishing-adventure\/\" class=\"plain\">NEUER SEE-REKORDKARPFEN BEI FISHING ADVENTURE 29,1 KG<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">02<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Juli<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:65%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.fishingadventure.nl\/de\/meeting-van-de-monsters-open-air-hengelsportbeurs-bij-fishing-adventure\/\" class=\"plain\" aria-label=\"Treffen der MONSTERS Open-Air-Angelmesse bei Fishing Adventure\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/01\/Organisatie-Bellyfiction-met-spandoek-2022-01-15-300x225.jpg?lossy=1&strip=1&webp=1\" class=\"attachment-medium size-medium wp-post-image lazyload\" alt=\"Open Air Hengelsportbeurs\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/01\/Organisatie-Bellyfiction-met-spandoek-2022-01-15-300x225.jpg?lossy=1&strip=1&webp=1 300w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/01\/Organisatie-Bellyfiction-met-spandoek-2022-01-15-510x383.jpg?lossy=1&strip=1&webp=1 510w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/01\/Organisatie-Bellyfiction-met-spandoek-2022-01-15-1024x768.jpg?lossy=1&strip=1&webp=1 1024w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/01\/Organisatie-Bellyfiction-met-spandoek-2022-01-15-768x576.jpg?lossy=1&strip=1&webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/01\/Organisatie-Bellyfiction-met-spandoek-2022-01-15-1536x1152.jpg?lossy=1&strip=1&webp=1 1536w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/01\/Organisatie-Bellyfiction-met-spandoek-2022-01-15-16x12.jpg?lossy=1&strip=1&webp=1 16w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/01\/Organisatie-Bellyfiction-met-spandoek-2022-01-15-600x450.jpg?lossy=1&strip=1&webp=1 600w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/01\/Organisatie-Bellyfiction-met-spandoek-2022-01-15.jpg?lossy=1&strip=1&webp=1 2000w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2022\/01\/Organisatie-Bellyfiction-met-spandoek-2022-01-15.jpg?size=204x153&lossy=1&strip=1&webp=1 204w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/225;\" data-original-sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0, 0, 0, 0.448)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center is-small\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.fishingadventure.nl\/de\/meeting-van-de-monsters-open-air-hengelsportbeurs-bij-fishing-adventure\/\" class=\"plain\">Treffen der MONSTERS Open-Air-Angelmesse bei Fishing Adventure<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">16<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Jan.<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:65%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.fishingadventure.nl\/de\/nieuw-meerrecord-576-pond\/\" class=\"plain\" aria-label=\"NEUER SEEREKORD 57,6 PFUND\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"200\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/10\/IMG-20211017-WA0009-300x200.jpg?lossy=1&strip=1&webp=1\" class=\"attachment-medium size-medium wp-post-image lazyload\" alt=\"NIEUW MEERRECORD 57,6 POND\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/10\/IMG-20211017-WA0009-300x200.jpg?lossy=1&strip=1&webp=1 300w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/10\/IMG-20211017-WA0009-1024x683.jpg?lossy=1&strip=1&webp=1 1024w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/10\/IMG-20211017-WA0009-768x512.jpg?lossy=1&strip=1&webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/10\/IMG-20211017-WA0009-1536x1024.jpg?lossy=1&strip=1&webp=1 1536w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/10\/IMG-20211017-WA0009-18x12.jpg?lossy=1&strip=1&webp=1 18w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/10\/IMG-20211017-WA0009-600x400.jpg?lossy=1&strip=1&webp=1 600w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/10\/IMG-20211017-WA0009.jpg?lossy=1&strip=1&webp=1 1620w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/10\/IMG-20211017-WA0009.jpg?size=204x136&lossy=1&strip=1&webp=1 204w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/200;\" data-original-sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0, 0, 0, 0.448)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center is-small\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.fishingadventure.nl\/de\/nieuw-meerrecord-576-pond\/\" class=\"plain\">NEUER SEEREKORD 57,6 PFUND<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">17<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Okt.<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:65%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.fishingadventure.nl\/de\/big-fish-event-7-april-2022\/\" class=\"plain\" aria-label=\"Gro\u00dffischveranstaltung 7. April 2022\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"212\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/09\/Big-Fish-april-2022-1-300x212.jpg?lossy=1&strip=1&webp=1\" class=\"attachment-medium size-medium wp-post-image lazyload\" alt=\"Big Fish april 2022 1\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/09\/Big-Fish-april-2022-1-300x212.jpg?lossy=1&strip=1&webp=1 300w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/09\/Big-Fish-april-2022-1-510x361.jpg?lossy=1&strip=1&webp=1 510w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/09\/Big-Fish-april-2022-1-1024x724.jpg?lossy=1&strip=1&webp=1 1024w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/09\/Big-Fish-april-2022-1-768x543.jpg?lossy=1&strip=1&webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/09\/Big-Fish-april-2022-1-1536x1086.jpg?lossy=1&strip=1&webp=1 1536w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/09\/Big-Fish-april-2022-1-18x12.jpg?lossy=1&strip=1&webp=1 18w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/09\/Big-Fish-april-2022-1-600x424.jpg?lossy=1&strip=1&webp=1 600w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/09\/Big-Fish-april-2022-1.jpg?lossy=1&strip=1&webp=1 1755w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2021\/09\/Big-Fish-april-2022-1.jpg?size=204x144&lossy=1&strip=1&webp=1 204w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/212;\" data-original-sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0, 0, 0, 0.448)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center is-small\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.fishingadventure.nl\/de\/big-fish-event-7-april-2022\/\" class=\"plain\">Gro\u00dffischveranstaltung 7. April 2022<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">08<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Sep.<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-711935162 > .col-inner {\n  padding: 0px 0px 0px 0px;\n  margin: 0px 0px -15px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row row-small\"  id=\"row-573745041\">\n\n\n\t<div id=\"col-1305311215\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h2>Unsere Boilies<\/h2>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1305311215 > .col-inner {\n  margin: 0px 0px -20px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1507566825\" class=\"col medium-3 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t<a href=\"https:\/\/www.fabaits.nl\/product\/chunky-munkey-readymade-boilies\/\" target=\"_blank\" rel=\"noopener\">\t\t\t<div class=\"image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t<img decoding=\"async\" width=\"829\" height=\"1400\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/09\/Chunky-Munkey-Readymade-Boilies-5KG.jpg?lossy=1&strip=1&webp=1\" class=\"attachment- size- lazyload\" alt=\"Chunky Munkey Readymade Boilies 5KG\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/09\/Chunky-Munkey-Readymade-Boilies-5KG.jpg?lossy=1&strip=1&webp=1 829w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/09\/Chunky-Munkey-Readymade-Boilies-5KG-178x300.jpg?lossy=1&strip=1&webp=1 178w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/09\/Chunky-Munkey-Readymade-Boilies-5KG-606x1024.jpg?lossy=1&strip=1&webp=1 606w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/09\/Chunky-Munkey-Readymade-Boilies-5KG-768x1297.jpg?lossy=1&strip=1&webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/09\/Chunky-Munkey-Readymade-Boilies-5KG-7x12.jpg?lossy=1&strip=1&webp=1 7w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/09\/Chunky-Munkey-Readymade-Boilies-5KG-510x861.jpg?lossy=1&strip=1&webp=1 510w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/09\/Chunky-Munkey-Readymade-Boilies-5KG.jpg?size=408x689&lossy=1&strip=1&webp=1 408w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 829px; --smush-placeholder-aspect-ratio: 829\/1400;\" data-original-sizes=\"(max-width: 829px) 100vw, 829px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n\t<div id=\"text-765865069\" class=\"text\">\n\t\t\n\n<h4>Chunky Munkey<\/h4>\n<p>Fertige Boilies 5KG<\/p>\n\t\t\n<style>\n#text-765865069 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-277216550\" class=\"col medium-3 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t<a href=\"https:\/\/www.fabaits.nl\/product\/robin-red-garlic-readymade-boilies-5kg\/\" target=\"_blank\" rel=\"noopener\">\t\t\t<div class=\"image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t<img decoding=\"async\" width=\"829\" height=\"1400\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/09\/Robin-Red-Garlic-Readymade-Boilies-5KG.jpg?lossy=1&strip=1&webp=1\" class=\"attachment- size- lazyload\" alt=\"Robin Red Garlic Readymade Boilies 5KG\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/09\/Robin-Red-Garlic-Readymade-Boilies-5KG.jpg?lossy=1&strip=1&webp=1 829w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/09\/Robin-Red-Garlic-Readymade-Boilies-5KG-178x300.jpg?lossy=1&strip=1&webp=1 178w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/09\/Robin-Red-Garlic-Readymade-Boilies-5KG-606x1024.jpg?lossy=1&strip=1&webp=1 606w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/09\/Robin-Red-Garlic-Readymade-Boilies-5KG-768x1297.jpg?lossy=1&strip=1&webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/09\/Robin-Red-Garlic-Readymade-Boilies-5KG-7x12.jpg?lossy=1&strip=1&webp=1 7w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/09\/Robin-Red-Garlic-Readymade-Boilies-5KG-510x861.jpg?lossy=1&strip=1&webp=1 510w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/09\/Robin-Red-Garlic-Readymade-Boilies-5KG.jpg?size=408x689&lossy=1&strip=1&webp=1 408w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 829px; --smush-placeholder-aspect-ratio: 829\/1400;\" data-original-sizes=\"(max-width: 829px) 100vw, 829px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n\t<div id=\"text-4115194948\" class=\"text\">\n\t\t\n\n<h4>Roter B\u00e4rlauch<\/h4>\n<p>Fertige Boilies 5KG<\/p>\n\t\t\n<style>\n#text-4115194948 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1203360641\" class=\"col medium-3 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t<a href=\"https:\/\/www.fabaits.nl\/product\/scoberry-spice-readymade-boilies-5kg\/\" target=\"_blank\" rel=\"noopener\">\t\t\t<div class=\"image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t<img decoding=\"async\" width=\"829\" height=\"1400\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/09\/Scoberry-Birdfood-Readymade-Boilies-5KG.jpg?lossy=1&strip=1&webp=1\" class=\"attachment- size- lazyload\" alt=\"Scoberry spice Readymade Boilies 5KG\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/09\/Scoberry-Birdfood-Readymade-Boilies-5KG.jpg?lossy=1&strip=1&webp=1 829w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/09\/Scoberry-Birdfood-Readymade-Boilies-5KG-178x300.jpg?lossy=1&strip=1&webp=1 178w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/09\/Scoberry-Birdfood-Readymade-Boilies-5KG-606x1024.jpg?lossy=1&strip=1&webp=1 606w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/09\/Scoberry-Birdfood-Readymade-Boilies-5KG-768x1297.jpg?lossy=1&strip=1&webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/09\/Scoberry-Birdfood-Readymade-Boilies-5KG-7x12.jpg?lossy=1&strip=1&webp=1 7w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/09\/Scoberry-Birdfood-Readymade-Boilies-5KG-510x861.jpg?lossy=1&strip=1&webp=1 510w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/09\/Scoberry-Birdfood-Readymade-Boilies-5KG.jpg?size=408x689&lossy=1&strip=1&webp=1 408w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 829px; --smush-placeholder-aspect-ratio: 829\/1400;\" data-original-sizes=\"(max-width: 829px) 100vw, 829px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n\t<div id=\"text-3513354896\" class=\"text\">\n\t\t\n\n<h4>Scoberry-Gew\u00fcrz<\/h4>\n<p>Fertige Boilies 5KG<\/p>\n\t\t\n<style>\n#text-3513354896 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-88868506\" class=\"col medium-3 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t<a href=\"https:\/\/www.fabaits.nl\/product\/bloody-krill-readymade-boilies-5kg\/\" target=\"_blank\" rel=\"noopener\">\t\t\t<div class=\"image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t<img decoding=\"async\" width=\"829\" height=\"1400\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/09\/Bloody-Krill-Readymade-Boilies-5KG.jpg?lossy=1&strip=1&webp=1\" class=\"attachment- size- lazyload\" alt=\"Bloody Kril Readymade Boilies a5KG\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/09\/Bloody-Krill-Readymade-Boilies-5KG.jpg?lossy=1&strip=1&webp=1 829w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/09\/Bloody-Krill-Readymade-Boilies-5KG-178x300.jpg?lossy=1&strip=1&webp=1 178w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/09\/Bloody-Krill-Readymade-Boilies-5KG-606x1024.jpg?lossy=1&strip=1&webp=1 606w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/09\/Bloody-Krill-Readymade-Boilies-5KG-768x1297.jpg?lossy=1&strip=1&webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/09\/Bloody-Krill-Readymade-Boilies-5KG-7x12.jpg?lossy=1&strip=1&webp=1 7w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/09\/Bloody-Krill-Readymade-Boilies-5KG-510x861.jpg?lossy=1&strip=1&webp=1 510w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/09\/Bloody-Krill-Readymade-Boilies-5KG.jpg?size=408x689&lossy=1&strip=1&webp=1 408w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 829px; --smush-placeholder-aspect-ratio: 829\/1400;\" data-original-sizes=\"(max-width: 829px) 100vw, 829px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n\t<div id=\"text-2691859652\" class=\"text\">\n\t\t\n\n<h4>Blutiger Krill<\/h4>\n<p>Fertige Boilies 5KG<\/p>\n\t\t\n<style>\n#text-2691859652 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1254331 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section has-parallax\" id=\"section_935056997\">\n\t\t<div class=\"section-bg fill\" data-parallax-container=\".section\" data-parallax-background data-parallax=\"-5\">\n\t\t\t<img decoding=\"async\" width=\"1920\" height=\"1087\" data-src=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/02\/Fishing-Adventure-Lake-Barbecue.jpeg?lossy=1&strip=1&webp=1\" class=\"bg attachment-original size-original lazyload\" alt=\"\" data-srcset=\"https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/02\/Fishing-Adventure-Lake-Barbecue.jpeg?lossy=1&amp;strip=1&amp;webp=1 1920w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/02\/Fishing-Adventure-Lake-Barbecue-300x170.jpeg?lossy=1&amp;strip=1&amp;webp=1 300w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/02\/Fishing-Adventure-Lake-Barbecue-1024x580.jpeg?lossy=1&amp;strip=1&amp;webp=1 1024w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/02\/Fishing-Adventure-Lake-Barbecue-768x435.jpeg?lossy=1&amp;strip=1&amp;webp=1 768w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/02\/Fishing-Adventure-Lake-Barbecue-1536x870.jpeg?lossy=1&amp;strip=1&amp;webp=1 1536w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/02\/Fishing-Adventure-Lake-Barbecue-18x10.jpeg?lossy=1&amp;strip=1&amp;webp=1 18w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/02\/Fishing-Adventure-Lake-Barbecue-510x289.jpeg?lossy=1&amp;strip=1&amp;webp=1 510w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/02\/Fishing-Adventure-Lake-Barbecue.jpeg?size=204x115&amp;lossy=1&amp;strip=1&amp;webp=1 204w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/02\/Fishing-Adventure-Lake-Barbecue.jpeg?size=408x231&amp;lossy=1&amp;strip=1&amp;webp=1 408w, https:\/\/b2983561.smushcdn.com\/2983561\/wp-content\/uploads\/2024\/02\/Fishing-Adventure-Lake-Barbecue.jpeg?size=612x346&amp;lossy=1&amp;strip=1&amp;webp=1 612w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1920px; --smush-placeholder-aspect-ratio: 1920\/1087;\" data-original-sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t<div class=\"section-bg-overlay absolute fill\"><\/div>\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:0px 0px 0px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-660569529\">\n\n\n\t<div id=\"col-1911103754\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-2235199482\" class=\"text\">\n\t\t\n\n<h2>Gem\u00fctliches Abenteuer mit Freunden und Familie<\/h2>\n<p>Fishing Adventure, das gr\u00f6\u00dfte Lohngew\u00e4sser der Niederlande, ist der richtige Ort f\u00fcr eine sch\u00f6ne Zeit an der frischen Luft. Ob Sie mit Ihrer Gruppe von Freunden, Familie oder Kollegen kommen - hier k\u00f6nnen Sie gemeinsam ein turbulentes Abenteuer erleben. Angeln, lachen, mit dem Golfwagen fahren und in der Natur entspannen: alles ist m\u00f6glich f\u00fcr einen actionreichen Tag mit guter Stimmung. Gemeinsam Erinnerungen am Wasser schaffen, darum geht es.<\/p>\n\t\t\n<style>\n#text-2235199482 {\n  font-size: 1.1rem;\n  text-align: center;\n  color: rgb(255, 255, 255);\n}\n#text-2235199482 > * {\n  color: rgb(255, 255, 255);\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"https:\/\/www.fishingadventure.nl\/de\/activiteiten\/\" class=\"button white\">\n\t\t<span>Unsere Aktivit\u00e4ten<\/span>\n\t<\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_935056997 {\n  padding-top: 52px;\n  padding-bottom: 52px;\n}\n#section_935056997 .section-bg-overlay {\n  background-color: rgba(0, 0, 0, 0.448);\n}\n#section_935056997 .section-bg img {\n  object-position: 68% 5%;\n}\n@media (min-width:550px) {\n  #section_935056997 {\n    padding-top: 91px;\n    padding-bottom: 91px;\n  }\n}\n<\/style>\n\t<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":7694,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"footnotes":""},"class_list":["post-5600","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/www.fishingadventure.nl\/de\/wp-json\/wp\/v2\/pages\/5600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fishingadventure.nl\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.fishingadventure.nl\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.fishingadventure.nl\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fishingadventure.nl\/de\/wp-json\/wp\/v2\/comments?post=5600"}],"version-history":[{"count":0,"href":"https:\/\/www.fishingadventure.nl\/de\/wp-json\/wp\/v2\/pages\/5600\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fishingadventure.nl\/de\/wp-json\/wp\/v2\/media\/7694"}],"wp:attachment":[{"href":"https:\/\/www.fishingadventure.nl\/de\/wp-json\/wp\/v2\/media?parent=5600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}